{"id":3263,"count":7,"description":"","link":"https:\/\/blog.medel.com\/ru\/category\/%d1%81%d0%be%d0%b2%d0%b5%d1%82%d1%8b-%d0%b8-%d1%80%d0%b5%d0%ba%d0%be%d0%bc%d0%b5%d0%bd%d0%b4%d0%b0%d1%86%d0%b8%d0%b8\/%d1%81%d0%be%d0%b2%d0%b5%d1%82%d1%8b-%d0%b8-%d1%80%d0%b5%d0%ba%d0%be%d0%bc%d0%b5%d0%bd%d0%b4%d0%b0%d1%86%d0%b8%d0%b8-%d0%b4%d0%bb%d1%8f-%d0%b2%d0%b7%d1%80%d0%be%d1%81%d0%bb%d1%8b%d1%85\/","name":"\u0414\u043b\u044f \u0432\u0437\u0440\u043e\u0441\u043b\u044b\u0445","slug":"%d1%81%d0%be%d0%b2%d0%b5%d1%82%d1%8b-%d0%b8-%d1%80%d0%b5%d0%ba%d0%be%d0%bc%d0%b5%d0%bd%d0%b4%d0%b0%d1%86%d0%b8%d0%b8-%d0%b4%d0%bb%d1%8f-%d0%b2%d0%b7%d1%80%d0%be%d1%81%d0%bb%d1%8b%d1%85","taxonomy":"category","parent":3210,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u0414\u043b\u044f \u0432\u0437\u0440\u043e\u0441\u043b\u044b\u0445 Archives - The MED-EL Blog<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/blog.medel.com\/ru\/category\/\u0441\u043e\u0432\u0435\u0442\u044b-\u0438-\u0440\u0435\u043a\u043e\u043c\u0435\u043d\u0434\u0430\u0446\u0438\u0438\/\u0441\u043e\u0432\u0435\u0442\u044b-\u0438-\u0440\u0435\u043a\u043e\u043c\u0435\u043d\u0434\u0430\u0446\u0438\u0438-\u0434\u043b\u044f-\u0432\u0437\u0440\u043e\u0441\u043b\u044b\u0445\/\" \/>\n<meta property=\"og:locale\" content=\"ru_RU\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u0414\u043b\u044f \u0432\u0437\u0440\u043e\u0441\u043b\u044b\u0445 Archives - The MED-EL Blog\" \/>\n<meta property=\"og:url\" content=\"https:\/\/blog.medel.com\/ru\/category\/\u0441\u043e\u0432\u0435\u0442\u044b-\u0438-\u0440\u0435\u043a\u043e\u043c\u0435\u043d\u0434\u0430\u0446\u0438\u0438\/\u0441\u043e\u0432\u0435\u0442\u044b-\u0438-\u0440\u0435\u043a\u043e\u043c\u0435\u043d\u0434\u0430\u0446\u0438\u0438-\u0434\u043b\u044f-\u0432\u0437\u0440\u043e\u0441\u043b\u044b\u0445\/\" \/>\n<meta property=\"og:site_name\" content=\"The MED-EL Blog\" \/>\n<meta property=\"og:image\" content=\"https:\/\/blog.medel.com\/wp-content\/uploads\/2023\/02\/MED-EL_logo_L2.png\" \/>\n\t<meta property=\"og:image:width\" content=\"443\" \/>\n\t<meta property=\"og:image:height\" content=\"200\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/blog.medel.com\\\/ru\\\/category\\\/%d1%81%d0%be%d0%b2%d0%b5%d1%82%d1%8b-%d0%b8-%d1%80%d0%b5%d0%ba%d0%be%d0%bc%d0%b5%d0%bd%d0%b4%d0%b0%d1%86%d0%b8%d0%b8\\\/%d1%81%d0%be%d0%b2%d0%b5%d1%82%d1%8b-%d0%b8-%d1%80%d0%b5%d0%ba%d0%be%d0%bc%d0%b5%d0%bd%d0%b4%d0%b0%d1%86%d0%b8%d0%b8-%d0%b4%d0%bb%d1%8f-%d0%b2%d0%b7%d1%80%d0%be%d1%81%d0%bb%d1%8b%d1%85\\\/\",\"url\":\"https:\\\/\\\/blog.medel.com\\\/ru\\\/category\\\/%d1%81%d0%be%d0%b2%d0%b5%d1%82%d1%8b-%d0%b8-%d1%80%d0%b5%d0%ba%d0%be%d0%bc%d0%b5%d0%bd%d0%b4%d0%b0%d1%86%d0%b8%d0%b8\\\/%d1%81%d0%be%d0%b2%d0%b5%d1%82%d1%8b-%d0%b8-%d1%80%d0%b5%d0%ba%d0%be%d0%bc%d0%b5%d0%bd%d0%b4%d0%b0%d1%86%d0%b8%d0%b8-%d0%b4%d0%bb%d1%8f-%d0%b2%d0%b7%d1%80%d0%be%d1%81%d0%bb%d1%8b%d1%85\\\/\",\"name\":\"\u0414\u043b\u044f \u0432\u0437\u0440\u043e\u0441\u043b\u044b\u0445 Archives - The MED-EL Blog\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blog.medel.com\\\/de\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/blog.medel.com\\\/ru\\\/category\\\/%d1%81%d0%be%d0%b2%d0%b5%d1%82%d1%8b-%d0%b8-%d1%80%d0%b5%d0%ba%d0%be%d0%bc%d0%b5%d0%bd%d0%b4%d0%b0%d1%86%d0%b8%d0%b8\\\/%d1%81%d0%be%d0%b2%d0%b5%d1%82%d1%8b-%d0%b8-%d1%80%d0%b5%d0%ba%d0%be%d0%bc%d0%b5%d0%bd%d0%b4%d0%b0%d1%86%d0%b8%d0%b8-%d0%b4%d0%bb%d1%8f-%d0%b2%d0%b7%d1%80%d0%be%d1%81%d0%bb%d1%8b%d1%85\\\/#breadcrumb\"},\"inLanguage\":\"ru-RU\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/blog.medel.com\\\/ru\\\/category\\\/%d1%81%d0%be%d0%b2%d0%b5%d1%82%d1%8b-%d0%b8-%d1%80%d0%b5%d0%ba%d0%be%d0%bc%d0%b5%d0%bd%d0%b4%d0%b0%d1%86%d0%b8%d0%b8\\\/%d1%81%d0%be%d0%b2%d0%b5%d1%82%d1%8b-%d0%b8-%d1%80%d0%b5%d0%ba%d0%be%d0%bc%d0%b5%d0%bd%d0%b4%d0%b0%d1%86%d0%b8%d0%b8-%d0%b4%d0%bb%d1%8f-%d0%b2%d0%b7%d1%80%d0%be%d1%81%d0%bb%d1%8b%d1%85\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/blog.medel.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tips &amp; Tricks\",\"item\":\"https:\\\/\\\/blog.medel.com\\\/category\\\/tips-tricks\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"\u0414\u043b\u044f \u0432\u0437\u0440\u043e\u0441\u043b\u044b\u0445\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/blog.medel.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/blog.medel.com\\\/de\\\/\",\"name\":\"The MED-EL Blog\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/blog.medel.com\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/blog.medel.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ru-RU\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/blog.medel.com\\\/de\\\/#organization\",\"name\":\"The MED-EL Blog\",\"url\":\"https:\\\/\\\/blog.medel.com\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ru-RU\",\"@id\":\"https:\\\/\\\/blog.medel.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/blog.medel.com\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/MED-EL_logo_L2.png\",\"contentUrl\":\"https:\\\/\\\/blog.medel.com\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/MED-EL_logo_L2.png\",\"width\":443,\"height\":200,\"caption\":\"The MED-EL Blog\"},\"image\":{\"@id\":\"https:\\\/\\\/blog.medel.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u0414\u043b\u044f \u0432\u0437\u0440\u043e\u0441\u043b\u044b\u0445 Archives - The MED-EL Blog","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/blog.medel.com\/ru\/category\/\u0441\u043e\u0432\u0435\u0442\u044b-\u0438-\u0440\u0435\u043a\u043e\u043c\u0435\u043d\u0434\u0430\u0446\u0438\u0438\/\u0441\u043e\u0432\u0435\u0442\u044b-\u0438-\u0440\u0435\u043a\u043e\u043c\u0435\u043d\u0434\u0430\u0446\u0438\u0438-\u0434\u043b\u044f-\u0432\u0437\u0440\u043e\u0441\u043b\u044b\u0445\/","og_locale":"ru_RU","og_type":"article","og_title":"\u0414\u043b\u044f \u0432\u0437\u0440\u043e\u0441\u043b\u044b\u0445 Archives - The MED-EL Blog","og_url":"https:\/\/blog.medel.com\/ru\/category\/\u0441\u043e\u0432\u0435\u0442\u044b-\u0438-\u0440\u0435\u043a\u043e\u043c\u0435\u043d\u0434\u0430\u0446\u0438\u0438\/\u0441\u043e\u0432\u0435\u0442\u044b-\u0438-\u0440\u0435\u043a\u043e\u043c\u0435\u043d\u0434\u0430\u0446\u0438\u0438-\u0434\u043b\u044f-\u0432\u0437\u0440\u043e\u0441\u043b\u044b\u0445\/","og_site_name":"The MED-EL Blog","og_image":[{"width":443,"height":200,"url":"https:\/\/blog.medel.com\/wp-content\/uploads\/2023\/02\/MED-EL_logo_L2.png","type":"image\/png"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/blog.medel.com\/ru\/category\/%d1%81%d0%be%d0%b2%d0%b5%d1%82%d1%8b-%d0%b8-%d1%80%d0%b5%d0%ba%d0%be%d0%bc%d0%b5%d0%bd%d0%b4%d0%b0%d1%86%d0%b8%d0%b8\/%d1%81%d0%be%d0%b2%d0%b5%d1%82%d1%8b-%d0%b8-%d1%80%d0%b5%d0%ba%d0%be%d0%bc%d0%b5%d0%bd%d0%b4%d0%b0%d1%86%d0%b8%d0%b8-%d0%b4%d0%bb%d1%8f-%d0%b2%d0%b7%d1%80%d0%be%d1%81%d0%bb%d1%8b%d1%85\/","url":"https:\/\/blog.medel.com\/ru\/category\/%d1%81%d0%be%d0%b2%d0%b5%d1%82%d1%8b-%d0%b8-%d1%80%d0%b5%d0%ba%d0%be%d0%bc%d0%b5%d0%bd%d0%b4%d0%b0%d1%86%d0%b8%d0%b8\/%d1%81%d0%be%d0%b2%d0%b5%d1%82%d1%8b-%d0%b8-%d1%80%d0%b5%d0%ba%d0%be%d0%bc%d0%b5%d0%bd%d0%b4%d0%b0%d1%86%d0%b8%d0%b8-%d0%b4%d0%bb%d1%8f-%d0%b2%d0%b7%d1%80%d0%be%d1%81%d0%bb%d1%8b%d1%85\/","name":"\u0414\u043b\u044f \u0432\u0437\u0440\u043e\u0441\u043b\u044b\u0445 Archives - The MED-EL Blog","isPartOf":{"@id":"https:\/\/blog.medel.com\/de\/#website"},"breadcrumb":{"@id":"https:\/\/blog.medel.com\/ru\/category\/%d1%81%d0%be%d0%b2%d0%b5%d1%82%d1%8b-%d0%b8-%d1%80%d0%b5%d0%ba%d0%be%d0%bc%d0%b5%d0%bd%d0%b4%d0%b0%d1%86%d0%b8%d0%b8\/%d1%81%d0%be%d0%b2%d0%b5%d1%82%d1%8b-%d0%b8-%d1%80%d0%b5%d0%ba%d0%be%d0%bc%d0%b5%d0%bd%d0%b4%d0%b0%d1%86%d0%b8%d0%b8-%d0%b4%d0%bb%d1%8f-%d0%b2%d0%b7%d1%80%d0%be%d1%81%d0%bb%d1%8b%d1%85\/#breadcrumb"},"inLanguage":"ru-RU"},{"@type":"BreadcrumbList","@id":"https:\/\/blog.medel.com\/ru\/category\/%d1%81%d0%be%d0%b2%d0%b5%d1%82%d1%8b-%d0%b8-%d1%80%d0%b5%d0%ba%d0%be%d0%bc%d0%b5%d0%bd%d0%b4%d0%b0%d1%86%d0%b8%d0%b8\/%d1%81%d0%be%d0%b2%d0%b5%d1%82%d1%8b-%d0%b8-%d1%80%d0%b5%d0%ba%d0%be%d0%bc%d0%b5%d0%bd%d0%b4%d0%b0%d1%86%d0%b8%d0%b8-%d0%b4%d0%bb%d1%8f-%d0%b2%d0%b7%d1%80%d0%be%d1%81%d0%bb%d1%8b%d1%85\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/blog.medel.com\/"},{"@type":"ListItem","position":2,"name":"Tips &amp; Tricks","item":"https:\/\/blog.medel.com\/category\/tips-tricks\/"},{"@type":"ListItem","position":3,"name":"\u0414\u043b\u044f \u0432\u0437\u0440\u043e\u0441\u043b\u044b\u0445"}]},{"@type":"WebSite","@id":"https:\/\/blog.medel.com\/de\/#website","url":"https:\/\/blog.medel.com\/de\/","name":"The MED-EL Blog","description":"","publisher":{"@id":"https:\/\/blog.medel.com\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/blog.medel.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ru-RU"},{"@type":"Organization","@id":"https:\/\/blog.medel.com\/de\/#organization","name":"The MED-EL Blog","url":"https:\/\/blog.medel.com\/de\/","logo":{"@type":"ImageObject","inLanguage":"ru-RU","@id":"https:\/\/blog.medel.com\/de\/#\/schema\/logo\/image\/","url":"https:\/\/blog.medel.com\/wp-content\/uploads\/2023\/02\/MED-EL_logo_L2.png","contentUrl":"https:\/\/blog.medel.com\/wp-content\/uploads\/2023\/02\/MED-EL_logo_L2.png","width":443,"height":200,"caption":"The MED-EL Blog"},"image":{"@id":"https:\/\/blog.medel.com\/de\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/blog.medel.com\/ru\/wp-json\/wp\/v2\/categories\/3263","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.medel.com\/ru\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/blog.medel.com\/ru\/wp-json\/wp\/v2\/taxonomies\/category"}],"up":[{"embeddable":true,"href":"https:\/\/blog.medel.com\/ru\/wp-json\/wp\/v2\/categories\/3210"}],"wp:post_type":[{"href":"https:\/\/blog.medel.com\/ru\/wp-json\/wp\/v2\/posts?categories=3263"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}