{"id":53603,"date":"2020-05-28T18:00:49","date_gmt":"2020-05-28T18:00:49","guid":{"rendered":"https:\/\/blog.medel.com\/uncategorized-latam\/el-implante-coclear-mejoro-la-vida-de-guillermo\/"},"modified":"2023-12-04T16:09:12","modified_gmt":"2023-12-04T14:09:12","slug":"el-implante-coclear-mejoro-la-vida-de-guillermo","status":"publish","type":"post","link":"https:\/\/blog.medel.com\/latam\/historias-de-usuarios-latam\/el-implante-coclear-mejoro-la-vida-de-guillermo\/","title":{"rendered":"El Implante Coclear mejor\u00f3 la vida de Guillermo"},"content":{"rendered":"<p><em>Mi nombre es Jos\u00e9 Guillermo Rodr\u00edguez Linares, soy Administrador de Empresas y me dedico a la Consultor\u00eda en desarrollo Organizacional y Liderazgo.<\/em><\/p>\n<hr \/>\n<h3><strong>\u00bfC\u00f3mo fue que descubriste tu p\u00e9rdida de audici\u00f3n? \u00bfQu\u00e9 edad ten\u00edas en ese momento?<\/strong><\/h3>\n<p>Ten\u00eda 51 a\u00f1os cuando las personas cercanas me dec\u00edan que cuando hablaba por celular lo hac\u00eda muy fuerte, con un volumen muy alto. Adem\u00e1s, cuando llegaba a mi casa en las noches yme encontraba en un espacio m\u00e1s tranquilo y sin ruidos de la calle sent\u00eda un pito-zumbido, <strong>un Tinnitus<\/strong>. Entonces decid\u00ed consultar al m\u00e9dico y descubrieron a trav\u00e9s de una audiometr\u00eda que hab\u00eda perdido el 70% de la audici\u00f3n en el o\u00eddo derecho en los sonidos agudos. Iniciaron los ex\u00e1menes y descubrieron que ten\u00eda un Schawannoma Intrac\u00f3clear, un tumor benigno dentro de la c\u00f3clea.<\/p>\n<p>Desde el a\u00f1o 2013 al 2016 fui perdiendo poco a poco la audici\u00f3n, hasta que en enero del 2016 perd\u00ed el 100% de audici\u00f3n del o\u00eddo derecho.<\/p>\n<p>&nbsp;<\/p>\n<h3><strong>\u00bfFue restrictiva tu hipoacusia en tu proceso escolar o laboral?<\/strong><\/h3>\n<p>S\u00ed fue restrictiva en el proceso laboral ya que como consultor dicto conferencias en salones donde asisten muchas personas, y se me dificultaba identificar la fuente sonora, la fuente de donde me hac\u00edan preguntas o me hablaban. Tambi\u00e9n en reuniones o lugares p\u00fablicos se me dificultaba la compresi\u00f3n y discriminaci\u00f3n de las conversaciones.<\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<h3><strong>\u00bfHubo alguna situaci\u00f3n particular que te llev\u00f3 a tomar la decisi\u00f3n de recibir un Implante Coclear?<\/strong><\/h3>\n<p>S\u00ed. Mejorar mi calidad de vida, tanto en las comunicaciones personales y familiares, como en la actividad laboral, dictando conferencias.<\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<h3><strong>\u00bfC\u00f3mo conociste las Soluciones Auditivas de MED-EL? \u00bfQu\u00e9 Procesador externo e Implante usas actualmente?<\/strong><\/h3>\n<p>Un excelente Ot\u00f3logo colombiano me practic\u00f3 la cirug\u00eda de Implante Coclear exitosamente. \u00c9l me recomend\u00f3 conocer las diferentes marcas de implantes y as\u00ed en reuni\u00f3n con los Distribuidores de MED-EL en Colombia recib\u00ed una muy buena informaci\u00f3n del Implante y sus beneficios, esto me anim\u00f3 a tomar decisi\u00f3n de optar por un Implante Coclear MED-EL <a href=\"https:\/\/www.medel.com\/latam\/hearing-solutions\/cochlear-implants\"><strong>SYNCHRONY<\/strong><\/a><strong> Flex 28<\/strong> y un Procesador de Audio <a href=\"https:\/\/www.medel.com\/latam\/support\/audio-processors\/rondo2\"><strong>RONDO 2.<\/strong><\/a><\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<h3><strong>\u00bfQu\u00e9 cambios o ventajas ha tra\u00eddo el Implante Coclear a tu vida cotidiana?<\/strong><\/h3>\n<p>De los cambios m\u00e1s importantes fue volver a escuchar por el o\u00eddo derecho, poder discriminar las palabras y tener un mayor entendimiento en las conversaciones. O\u00edr m\u00fasica, poder contestar una llamada por celular, escuchar audiolibros&#8230;<\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<h3><strong>\u00bfC\u00f3mo ayuda tu Implante Coclear en tu profesi\u00f3n como conferencista?<\/strong><\/h3>\n<p>En las conferencias ha mejorado en un buen porcentaje la identificaci\u00f3n de la fuente sonora, poder escuchar mejor a los participantes.<\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<h3><strong>\u00bfC\u00f3mo ha sido tu proceso de Rehabilitaci\u00f3n? \u00bfQui\u00e9n te ha acompa\u00f1ado durante este proceso y qu\u00e9 importancia ha tenido?<\/strong><\/h3>\n<p>El proceso de Rehabilitaci\u00f3n ha sido fundamental, en mi nivel de escucha y discriminaci\u00f3n que tengo hoy, el acompa\u00f1amiento en las sesiones semanales y el profesionalismo de la Dra. Betty Delgado, Fonoaudi\u00f3loga de Disortho, es excelente.<\/p>\n<p>Creo que el excelso equipo cl\u00ednico que realiz\u00f3 la cirug\u00eda, un excelente Implante de MED-EL, la Rehabilitaci\u00f3n asistida, las programaciones con las Audi\u00f3logas, asistir semanalmente a las terapias y hacer ejercicios particularmente han sido la clave del \u00e9xito con mi implante.<\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<h3><strong>\u00bfQu\u00e9 recuerdas de la experiencia de la cirug\u00eda? \u00bfQu\u00e9 miedos tuviste y c\u00f3mo lograste superarlos?<\/strong><\/h3>\n<p>Especialmente en mi caso por tener un Schawannoma Intracoclear, era que el \u00edmplate no se pudiera hacer o que por la condici\u00f3n la probabilidad de \u00e9xito fuera muy baja. Tambi\u00e9n que tuviera algunas secuelas. Afortunadamente ninguna de estas preocupaciones me afect\u00f3 y la cirug\u00eda de mi Implante Coclear fue un \u00e9xito.<\/p>\n<p>&nbsp;<\/p>\n<h3><strong>\u00bfQu\u00e9 es lo que m\u00e1s disfrutas de tu Implante Coclear? \u00bfCu\u00e1les son tus sonidos favoritos?<\/strong><\/h3>\n<p>O\u00edr, escuchar mejor las conversaciones, no aislarme en las reuniones familiares, \u00a1Realmente volver a escuchar!<\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<h3><strong>\u00bfHay alg\u00fan mensaje que quieras compartir con las personas que tienen dudas sobre recibir un implante o que padecen de p\u00e9rdida auditiva actualmente?<\/strong><\/h3>\n<p><strong>\u00a0<\/strong>Si existe una probabilidad de volver a escuchar, no duden en hacerse el implante, es una maravilla, recuperamos calidad de vida.<\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p><em>\u00a1Muchas gracias por compartirnos tu experiencia!<\/em><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Mi nombre es Jos\u00e9 Guillermo Rodr\u00edguez Linares, soy Administrador de Empresas y me dedico a la Consultor\u00eda en desarrollo Organizacional y Liderazgo. \u00bfC\u00f3mo fue que descubriste tu p\u00e9rdida de audici\u00f3n? \u00bfQu\u00e9 edad ten\u00edas en ese momento? Ten\u00eda 51 a\u00f1os cuando las personas cercanas me dec\u00edan que cuando hablaba por celular lo hac\u00eda muy fuerte, con [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":70786,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3361],"tags":[3864,3384,3438],"class_list":["post-53603","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-historias-de-usuarios-latam","tag-colombia-latam","tag-testimonio-latam","tag-usuario-latam"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>El Implante Coclear mejor\u00f3 la vida de Guillermo - Blog MED-EL<\/title>\n<meta name=\"description\" content=\"Conoce el testimonio de Guillermo Rodr\u00edguez, un usuario de Implante Coclear de MED-EL que actualmente se dedica a dar conferencias y exposiciones,\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/blog.medel.com\/latam\/historias-de-usuarios-latam\/el-implante-coclear-mejoro-la-vida-de-guillermo\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El Implante Coclear mejor\u00f3 la vida de Guillermo - Blog MED-EL\" \/>\n<meta property=\"og:description\" content=\"Conoce el testimonio de Guillermo Rodr\u00edguez, un usuario de Implante Coclear de MED-EL que actualmente se dedica a dar conferencias y exposiciones,\" \/>\n<meta property=\"og:url\" content=\"https:\/\/blog.medel.com\/latam\/historias-de-usuarios-latam\/el-implante-coclear-mejoro-la-vida-de-guillermo\/\" \/>\n<meta property=\"og:site_name\" content=\"The MED-EL Blog\" \/>\n<meta property=\"article:published_time\" content=\"2020-05-28T18:00:49+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-12-04T14:09:12+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/blog.medel.com\/wp-content\/uploads\/2023\/03\/med-el-054547-scaled-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1921\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"MED-EL\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"MED-EL\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/blog.medel.com\\\/latam\\\/historias-de-usuarios-latam\\\/el-implante-coclear-mejoro-la-vida-de-guillermo\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blog.medel.com\\\/latam\\\/historias-de-usuarios-latam\\\/el-implante-coclear-mejoro-la-vida-de-guillermo\\\/\"},\"author\":{\"name\":\"MED-EL\",\"@id\":\"https:\\\/\\\/blog.medel.com\\\/#\\\/schema\\\/person\\\/9f8dcfb27ec87796d874e021602c56e2\"},\"headline\":\"El Implante Coclear mejor\u00f3 la vida de Guillermo\",\"datePublished\":\"2020-05-28T18:00:49+00:00\",\"dateModified\":\"2023-12-04T14:09:12+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/blog.medel.com\\\/latam\\\/historias-de-usuarios-latam\\\/el-implante-coclear-mejoro-la-vida-de-guillermo\\\/\"},\"wordCount\":730,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/blog.medel.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/blog.medel.com\\\/latam\\\/historias-de-usuarios-latam\\\/el-implante-coclear-mejoro-la-vida-de-guillermo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/blog.medel.com\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/med-el-054547-scaled-1.jpg\",\"keywords\":[\"Colombia\",\"testimonio\",\"usu\u00e1rio\"],\"articleSection\":[\"HISTORIAS DE USUARIOS\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/blog.medel.com\\\/latam\\\/historias-de-usuarios-latam\\\/el-implante-coclear-mejoro-la-vida-de-guillermo\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/blog.medel.com\\\/latam\\\/historias-de-usuarios-latam\\\/el-implante-coclear-mejoro-la-vida-de-guillermo\\\/\",\"url\":\"https:\\\/\\\/blog.medel.com\\\/latam\\\/historias-de-usuarios-latam\\\/el-implante-coclear-mejoro-la-vida-de-guillermo\\\/\",\"name\":\"El Implante Coclear mejor\u00f3 la vida de Guillermo - Blog MED-EL\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blog.medel.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/blog.medel.com\\\/latam\\\/historias-de-usuarios-latam\\\/el-implante-coclear-mejoro-la-vida-de-guillermo\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/blog.medel.com\\\/latam\\\/historias-de-usuarios-latam\\\/el-implante-coclear-mejoro-la-vida-de-guillermo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/blog.medel.com\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/med-el-054547-scaled-1.jpg\",\"datePublished\":\"2020-05-28T18:00:49+00:00\",\"dateModified\":\"2023-12-04T14:09:12+00:00\",\"description\":\"Conoce el testimonio de Guillermo Rodr\u00edguez, un usuario de Implante Coclear de MED-EL que actualmente se dedica a dar conferencias y exposiciones,\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/blog.medel.com\\\/latam\\\/historias-de-usuarios-latam\\\/el-implante-coclear-mejoro-la-vida-de-guillermo\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/blog.medel.com\\\/latam\\\/historias-de-usuarios-latam\\\/el-implante-coclear-mejoro-la-vida-de-guillermo\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/blog.medel.com\\\/latam\\\/historias-de-usuarios-latam\\\/el-implante-coclear-mejoro-la-vida-de-guillermo\\\/#primaryimage\",\"url\":\"https:\\\/\\\/blog.medel.com\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/med-el-054547-scaled-1.jpg\",\"contentUrl\":\"https:\\\/\\\/blog.medel.com\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/med-el-054547-scaled-1.jpg\",\"width\":2560,\"height\":1921},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/blog.medel.com\\\/latam\\\/historias-de-usuarios-latam\\\/el-implante-coclear-mejoro-la-vida-de-guillermo\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/blog.medel.com\\\/latam\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El Implante Coclear mejor\u00f3 la vida de Guillermo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/blog.medel.com\\\/#website\",\"url\":\"https:\\\/\\\/blog.medel.com\\\/\",\"name\":\"The MED-EL Blog\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/blog.medel.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/blog.medel.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/blog.medel.com\\\/#organization\",\"name\":\"The MED-EL Blog\",\"url\":\"https:\\\/\\\/blog.medel.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/blog.medel.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/blog.medel.com\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/MED-EL_logo_L2.png\",\"contentUrl\":\"https:\\\/\\\/blog.medel.com\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/MED-EL_logo_L2.png\",\"width\":443,\"height\":200,\"caption\":\"The MED-EL Blog\"},\"image\":{\"@id\":\"https:\\\/\\\/blog.medel.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/blog.medel.com\\\/#\\\/schema\\\/person\\\/9f8dcfb27ec87796d874e021602c56e2\",\"name\":\"MED-EL\",\"sameAs\":[\"https:\\\/\\\/www.medel.com\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El Implante Coclear mejor\u00f3 la vida de Guillermo - Blog MED-EL","description":"Conoce el testimonio de Guillermo Rodr\u00edguez, un usuario de Implante Coclear de MED-EL que actualmente se dedica a dar conferencias y exposiciones,","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/blog.medel.com\/latam\/historias-de-usuarios-latam\/el-implante-coclear-mejoro-la-vida-de-guillermo\/","og_locale":"es_ES","og_type":"article","og_title":"El Implante Coclear mejor\u00f3 la vida de Guillermo - Blog MED-EL","og_description":"Conoce el testimonio de Guillermo Rodr\u00edguez, un usuario de Implante Coclear de MED-EL que actualmente se dedica a dar conferencias y exposiciones,","og_url":"https:\/\/blog.medel.com\/latam\/historias-de-usuarios-latam\/el-implante-coclear-mejoro-la-vida-de-guillermo\/","og_site_name":"The MED-EL Blog","article_published_time":"2020-05-28T18:00:49+00:00","article_modified_time":"2023-12-04T14:09:12+00:00","og_image":[{"width":2560,"height":1921,"url":"https:\/\/blog.medel.com\/wp-content\/uploads\/2023\/03\/med-el-054547-scaled-1.jpg","type":"image\/jpeg"}],"author":"MED-EL","twitter_card":"summary_large_image","twitter_misc":{"Written by":"MED-EL","Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/blog.medel.com\/latam\/historias-de-usuarios-latam\/el-implante-coclear-mejoro-la-vida-de-guillermo\/#article","isPartOf":{"@id":"https:\/\/blog.medel.com\/latam\/historias-de-usuarios-latam\/el-implante-coclear-mejoro-la-vida-de-guillermo\/"},"author":{"name":"MED-EL","@id":"https:\/\/blog.medel.com\/#\/schema\/person\/9f8dcfb27ec87796d874e021602c56e2"},"headline":"El Implante Coclear mejor\u00f3 la vida de Guillermo","datePublished":"2020-05-28T18:00:49+00:00","dateModified":"2023-12-04T14:09:12+00:00","mainEntityOfPage":{"@id":"https:\/\/blog.medel.com\/latam\/historias-de-usuarios-latam\/el-implante-coclear-mejoro-la-vida-de-guillermo\/"},"wordCount":730,"commentCount":0,"publisher":{"@id":"https:\/\/blog.medel.com\/#organization"},"image":{"@id":"https:\/\/blog.medel.com\/latam\/historias-de-usuarios-latam\/el-implante-coclear-mejoro-la-vida-de-guillermo\/#primaryimage"},"thumbnailUrl":"https:\/\/blog.medel.com\/wp-content\/uploads\/2023\/03\/med-el-054547-scaled-1.jpg","keywords":["Colombia","testimonio","usu\u00e1rio"],"articleSection":["HISTORIAS DE USUARIOS"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/blog.medel.com\/latam\/historias-de-usuarios-latam\/el-implante-coclear-mejoro-la-vida-de-guillermo\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/blog.medel.com\/latam\/historias-de-usuarios-latam\/el-implante-coclear-mejoro-la-vida-de-guillermo\/","url":"https:\/\/blog.medel.com\/latam\/historias-de-usuarios-latam\/el-implante-coclear-mejoro-la-vida-de-guillermo\/","name":"El Implante Coclear mejor\u00f3 la vida de Guillermo - Blog MED-EL","isPartOf":{"@id":"https:\/\/blog.medel.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/blog.medel.com\/latam\/historias-de-usuarios-latam\/el-implante-coclear-mejoro-la-vida-de-guillermo\/#primaryimage"},"image":{"@id":"https:\/\/blog.medel.com\/latam\/historias-de-usuarios-latam\/el-implante-coclear-mejoro-la-vida-de-guillermo\/#primaryimage"},"thumbnailUrl":"https:\/\/blog.medel.com\/wp-content\/uploads\/2023\/03\/med-el-054547-scaled-1.jpg","datePublished":"2020-05-28T18:00:49+00:00","dateModified":"2023-12-04T14:09:12+00:00","description":"Conoce el testimonio de Guillermo Rodr\u00edguez, un usuario de Implante Coclear de MED-EL que actualmente se dedica a dar conferencias y exposiciones,","breadcrumb":{"@id":"https:\/\/blog.medel.com\/latam\/historias-de-usuarios-latam\/el-implante-coclear-mejoro-la-vida-de-guillermo\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/blog.medel.com\/latam\/historias-de-usuarios-latam\/el-implante-coclear-mejoro-la-vida-de-guillermo\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/blog.medel.com\/latam\/historias-de-usuarios-latam\/el-implante-coclear-mejoro-la-vida-de-guillermo\/#primaryimage","url":"https:\/\/blog.medel.com\/wp-content\/uploads\/2023\/03\/med-el-054547-scaled-1.jpg","contentUrl":"https:\/\/blog.medel.com\/wp-content\/uploads\/2023\/03\/med-el-054547-scaled-1.jpg","width":2560,"height":1921},{"@type":"BreadcrumbList","@id":"https:\/\/blog.medel.com\/latam\/historias-de-usuarios-latam\/el-implante-coclear-mejoro-la-vida-de-guillermo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/blog.medel.com\/latam\/"},{"@type":"ListItem","position":2,"name":"El Implante Coclear mejor\u00f3 la vida de Guillermo"}]},{"@type":"WebSite","@id":"https:\/\/blog.medel.com\/#website","url":"https:\/\/blog.medel.com\/","name":"The MED-EL Blog","description":"","publisher":{"@id":"https:\/\/blog.medel.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/blog.medel.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/blog.medel.com\/#organization","name":"The MED-EL Blog","url":"https:\/\/blog.medel.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/blog.medel.com\/#\/schema\/logo\/image\/","url":"https:\/\/blog.medel.com\/wp-content\/uploads\/2023\/02\/MED-EL_logo_L2.png","contentUrl":"https:\/\/blog.medel.com\/wp-content\/uploads\/2023\/02\/MED-EL_logo_L2.png","width":443,"height":200,"caption":"The MED-EL Blog"},"image":{"@id":"https:\/\/blog.medel.com\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/blog.medel.com\/#\/schema\/person\/9f8dcfb27ec87796d874e021602c56e2","name":"MED-EL","sameAs":["https:\/\/www.medel.com"]}]}},"_links":{"self":[{"href":"https:\/\/blog.medel.com\/latam\/wp-json\/wp\/v2\/posts\/53603","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.medel.com\/latam\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.medel.com\/latam\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.medel.com\/latam\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.medel.com\/latam\/wp-json\/wp\/v2\/comments?post=53603"}],"version-history":[{"count":1,"href":"https:\/\/blog.medel.com\/latam\/wp-json\/wp\/v2\/posts\/53603\/revisions"}],"predecessor-version":[{"id":53604,"href":"https:\/\/blog.medel.com\/latam\/wp-json\/wp\/v2\/posts\/53603\/revisions\/53604"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blog.medel.com\/latam\/wp-json\/wp\/v2\/media\/70786"}],"wp:attachment":[{"href":"https:\/\/blog.medel.com\/latam\/wp-json\/wp\/v2\/media?parent=53603"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.medel.com\/latam\/wp-json\/wp\/v2\/categories?post=53603"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.medel.com\/latam\/wp-json\/wp\/v2\/tags?post=53603"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}