{"id":53591,"date":"2020-04-17T20:34:57","date_gmt":"2020-04-17T20:34:57","guid":{"rendered":"https:\/\/blog.medel.com\/uncategorized-latam\/limpieza-de-tu-procesador-de-audio-guia-especial-referente-al-covid-19-coronavirus\/"},"modified":"2023-03-13T13:56:48","modified_gmt":"2023-03-13T13:56:48","slug":"limpieza-de-tu-procesador-de-audio-guia-especial-referente-al-covid-19-coronavirus","status":"publish","type":"post","link":"https:\/\/blog.medel.com\/latam\/consejos-y-recomendaciones-latam\/para-adultos-latam\/limpieza-de-tu-procesador-de-audio-guia-especial-referente-al-covid-19-coronavirus\/","title":{"rendered":"Limpieza de tu procesador de audio: Gu\u00eda especial referente al COVID-19 (Coronavirus)"},"content":{"rendered":"<p>Durante estos tiempos sin precedentes, la Organizaci\u00f3n Mundial de la Salud (OMS) ha comunicado sus gu\u00edas sobre higiene para saber c\u00f3mo podemos protegernos a nosotros mismos y a los dem\u00e1s de ser infectados con el COVID-19. Esta informaci\u00f3n <a href=\"https:\/\/www.who.int\/es\/emergencies\/diseases\/novel-coronavirus-2019\/advice-for-public\">se puede encontrar aqu\u00ed.<\/a><\/p>\n<h2>Limpieza de tu procesador de audio<\/h2>\n<p>Antes de manipular el procesador de audio o cualquiera de sus accesorios, recomendamos limpiarte las manos, como se muestra en las <a href=\"https:\/\/www.who.int\/gpsc\/clean_hands_protection\/en\/\">indicaciones proporcionadas por la OMS<\/a><\/p>\n<p>Limpia y seca tu procesador de audio, de acuerdo a las instrucciones espec\u00edficas\u00a0 del modelo que tengas, tal y como como se indica en el manual de usuario (ver el cap\u00edtulo \u201cCuidado y mantenimiento\u201d, secci\u00f3n \u201cMantenimiento\u201d).<\/p>\n<p>Adem\u00e1s, puedes obtener m\u00e1s informaci\u00f3n de consejos e instrucciones con respecto a la limpieza y mantenimiento de tu procesador de audio, viendo los tutoriales de MED-EL. Haz clic abajo en el link del procesador de audio que uses.<\/p>\n<ul>\n<li><a href=\"https:\/\/www.youtube.com\/playlist?list=PLbA-wSZM8qcwYPBvV4-LZMgwleUIPBFn4\">RONDO 2<\/a><\/li>\n<li><a href=\"https:\/\/www.youtube.com\/playlist?list=PLbA-wSZM8qcyd3W_01IbNtyAhMn0NZGQv\">ADHEAR<\/a><\/li>\n<li><a href=\"https:\/\/www.youtube.com\/playlist?list=PLbA-wSZM8qczJsadxfpAkf0CUOA50iW4O\">SAMBA<\/a><\/li>\n<li><a href=\"https:\/\/www.medel.com\/support\/audio-processors\/opus2\/basic-care\/opus2_basiccareandmaintenace\">OPUS 2<\/a><\/li>\n<li><a href=\"https:\/\/www.youtube.com\/playlist?list=PLbA-wSZM8qcxCJbWVbr0og3kyMBTr2wAt\">SONNET and SONNET EAS\u00a0<\/a><\/li>\n<li><a href=\"https:\/\/www.youtube.com\/playlist?list=PLbA-wSZM8qcxjkLsMzmOjggO6l2WVPNKP\">RONDO\u00a0<\/a><\/li>\n<\/ul>\n<p>Actualmente, no se tienen instrucciones de limpieza diferentes a las que recomendamos en nuestros tutoriales. Lo importante es que mantengas una higiene \u00f3ptima de tu procesador, si considera que estuvo expuesto a una posible contaminaci\u00f3n del virus.<\/p>\n<h2>Desinfecci\u00f3n de tu procesador de audio<\/h2>\n<p>Siguiendo cuidadosamente las indicaciones de limpieza, en general no es necesario que desinfectes tu procesador de audio con frecuencia. El uso frecuente y a largo plazo de desinfectantes no est\u00e1 aprobado por MED-EL y puede llevar a la degradaci\u00f3n de materiales, decoloraci\u00f3n y roturas en el encapsulado del dispositivo. Los materiales degradados podr\u00edan causar irritaci\u00f3n de la piel y\/o da\u00f1o.<\/p>\n<p>Sin embargo, si crees que tu procesador puede haberse contaminado, y quisieras desinfectarlo, por favor sigue los pasos que se muestran a continuaci\u00f3n.<\/p>\n<h3>Materiales<\/h3>\n<p>MED-EL recomienda el uso de toallitas de limpieza listas para usar impregnadas en una soluci\u00f3n de alcohol isopro\u00edlico al 70% y agua desionizada al 30%. Si dichas toallitas no estuvieran disponibles en tu zona puedes usar toallitas secas y sumergirlas en un l\u00edquido de limpieza similar.<\/p>\n<p>Las sustancias distintas a las mezclas de alcohol isopro\u00edlico al 70% y agua desionizada al 30% no han sido probadas por MED-EL y podr\u00edan llevar a la degradaci\u00f3n de los materiales, decoloraci\u00f3n y roturas del encapsulado incluso con una sola aplicaci\u00f3n.<\/p>\n<h3>Instrucciones<\/h3>\n<ol>\n<li>Lave y seque sus manos, y limpie el procesador de audio como se indic\u00f3 anteriormente en \u201cLimpieza de tu procesador de audio\u201d.<\/li>\n<li>Utiliza las toallitas limpiadoras para humedecer la superficie del dispositivo cuidadosamente.<\/li>\n<li>Permita que el l\u00edquido seque la superficie del dispositivo. No lo seque inmediatamente, ya que el l\u00edquido necesita tiempo para actuar en la superficie y tener un mejor efecto desinfectante:<\/li>\n<li>No aplique demasiado l\u00edquido en la superficie ya que podr\u00eda da\u00f1ar su procesador de audio.<\/li>\n<li><strong>Sea especialmente cauteloso cuando aplique el desinfectante cerca de aberturas como la del micr\u00f3fono.<\/strong><\/li>\n<li>Tenga cuidado cuando limpie cerca de las membranas para evitar que entre suciedad y residuos m\u00e1s adentro de las membranas.<\/li>\n<li>La sustancia se secar\u00e1 sola si se utiliza el desinfectante recomendado y no se aplica demasiado l\u00edquido. Si no es el caso, utilice un pa\u00f1o suave para secar cualquier l\u00edquido residual.<\/li>\n<li>El proceso de desinfecci\u00f3n se ha completado. Ahora lave o limpie sus manos despu\u00e9s de desinfectar el dispositivo.<\/li>\n<\/ol>\n<p>&nbsp;<\/p>\n<p>Si te surge cualquier duda una vez hayas consultado tu manual de usuario y esta gu\u00eda adicional, contacta con tu <a href=\"https:\/\/www.medel.com\/esl\/distribuidores\/\">representante local de MED-EL<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Durante estos tiempos sin precedentes, la Organizaci\u00f3n Mundial de la Salud (OMS) ha comunicado sus gu\u00edas sobre higiene para saber c\u00f3mo podemos protegernos a nosotros mismos y a los dem\u00e1s de ser infectados con el COVID-19. Esta informaci\u00f3n se puede encontrar aqu\u00ed. Limpieza de tu procesador de audio Antes de manipular el procesador de audio [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":70732,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3356,3357],"tags":[2369,2636,2637],"class_list":["post-53591","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-para-adultos-latam","category-para-padres-latam","tag-covid-19","tag-desinfeccion","tag-limpieza"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Limpieza de tu procesador de audio: Gu\u00eda especial referente al COVID-19 (Coronavirus) - Blog MED-EL<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/blog.medel.com\/latam\/consejos-y-recomendaciones-latam\/para-adultos-latam\/limpieza-de-tu-procesador-de-audio-guia-especial-referente-al-covid-19-coronavirus\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Limpieza de tu procesador de audio: Gu\u00eda especial referente al COVID-19 (Coronavirus) - Blog MED-EL\" \/>\n<meta property=\"og:description\" content=\"Durante estos tiempos sin precedentes, la Organizaci\u00f3n Mundial de la Salud (OMS) ha comunicado sus gu\u00edas sobre higiene para saber c\u00f3mo podemos protegernos a nosotros mismos y a los dem\u00e1s de ser infectados con el COVID-19. Esta informaci\u00f3n se puede encontrar aqu\u00ed. Limpieza de tu procesador de audio Antes de manipular el procesador de audio [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/blog.medel.com\/latam\/consejos-y-recomendaciones-latam\/para-adultos-latam\/limpieza-de-tu-procesador-de-audio-guia-especial-referente-al-covid-19-coronavirus\/\" \/>\n<meta property=\"og:site_name\" content=\"The MED-EL Blog\" \/>\n<meta property=\"article:published_time\" content=\"2020-04-17T20:34:57+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-03-13T13:56:48+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/blog.medel.com\/wp-content\/uploads\/2023\/03\/cleaning-audio-processor-coronavirus-1-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"400\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"MED-EL\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"MED-EL\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/blog.medel.com\\\/latam\\\/consejos-y-recomendaciones-latam\\\/para-adultos-latam\\\/limpieza-de-tu-procesador-de-audio-guia-especial-referente-al-covid-19-coronavirus\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blog.medel.com\\\/latam\\\/consejos-y-recomendaciones-latam\\\/para-adultos-latam\\\/limpieza-de-tu-procesador-de-audio-guia-especial-referente-al-covid-19-coronavirus\\\/\"},\"author\":{\"name\":\"MED-EL\",\"@id\":\"https:\\\/\\\/blog.medel.com\\\/de\\\/#\\\/schema\\\/person\\\/9f8dcfb27ec87796d874e021602c56e2\"},\"headline\":\"Limpieza de tu procesador de audio: Gu\u00eda especial referente al COVID-19 (Coronavirus)\",\"datePublished\":\"2020-04-17T20:34:57+00:00\",\"dateModified\":\"2023-03-13T13:56:48+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/blog.medel.com\\\/latam\\\/consejos-y-recomendaciones-latam\\\/para-adultos-latam\\\/limpieza-de-tu-procesador-de-audio-guia-especial-referente-al-covid-19-coronavirus\\\/\"},\"wordCount\":608,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/blog.medel.com\\\/de\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/blog.medel.com\\\/latam\\\/consejos-y-recomendaciones-latam\\\/para-adultos-latam\\\/limpieza-de-tu-procesador-de-audio-guia-especial-referente-al-covid-19-coronavirus\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/blog.medel.com\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/cleaning-audio-processor-coronavirus-1-1.jpg\",\"keywords\":[\"COVID-19\",\"Desinfecci\u00f3n\",\"LImpieza\"],\"articleSection\":[\"Para Adultos\",\"Para Padres\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/blog.medel.com\\\/latam\\\/consejos-y-recomendaciones-latam\\\/para-adultos-latam\\\/limpieza-de-tu-procesador-de-audio-guia-especial-referente-al-covid-19-coronavirus\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/blog.medel.com\\\/latam\\\/consejos-y-recomendaciones-latam\\\/para-adultos-latam\\\/limpieza-de-tu-procesador-de-audio-guia-especial-referente-al-covid-19-coronavirus\\\/\",\"url\":\"https:\\\/\\\/blog.medel.com\\\/latam\\\/consejos-y-recomendaciones-latam\\\/para-adultos-latam\\\/limpieza-de-tu-procesador-de-audio-guia-especial-referente-al-covid-19-coronavirus\\\/\",\"name\":\"Limpieza de tu procesador de audio: Gu\u00eda especial referente al COVID-19 (Coronavirus) - Blog MED-EL\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blog.medel.com\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/blog.medel.com\\\/latam\\\/consejos-y-recomendaciones-latam\\\/para-adultos-latam\\\/limpieza-de-tu-procesador-de-audio-guia-especial-referente-al-covid-19-coronavirus\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/blog.medel.com\\\/latam\\\/consejos-y-recomendaciones-latam\\\/para-adultos-latam\\\/limpieza-de-tu-procesador-de-audio-guia-especial-referente-al-covid-19-coronavirus\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/blog.medel.com\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/cleaning-audio-processor-coronavirus-1-1.jpg\",\"datePublished\":\"2020-04-17T20:34:57+00:00\",\"dateModified\":\"2023-03-13T13:56:48+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/blog.medel.com\\\/latam\\\/consejos-y-recomendaciones-latam\\\/para-adultos-latam\\\/limpieza-de-tu-procesador-de-audio-guia-especial-referente-al-covid-19-coronavirus\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/blog.medel.com\\\/latam\\\/consejos-y-recomendaciones-latam\\\/para-adultos-latam\\\/limpieza-de-tu-procesador-de-audio-guia-especial-referente-al-covid-19-coronavirus\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/blog.medel.com\\\/latam\\\/consejos-y-recomendaciones-latam\\\/para-adultos-latam\\\/limpieza-de-tu-procesador-de-audio-guia-especial-referente-al-covid-19-coronavirus\\\/#primaryimage\",\"url\":\"https:\\\/\\\/blog.medel.com\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/cleaning-audio-processor-coronavirus-1-1.jpg\",\"contentUrl\":\"https:\\\/\\\/blog.medel.com\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/cleaning-audio-processor-coronavirus-1-1.jpg\",\"width\":800,\"height\":400},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/blog.medel.com\\\/latam\\\/consejos-y-recomendaciones-latam\\\/para-adultos-latam\\\/limpieza-de-tu-procesador-de-audio-guia-especial-referente-al-covid-19-coronavirus\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/blog.medel.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Limpieza de tu procesador de audio: Gu\u00eda especial referente al COVID-19 (Coronavirus)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/blog.medel.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/blog.medel.com\\\/de\\\/\",\"name\":\"The MED-EL Blog\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/blog.medel.com\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/blog.medel.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/blog.medel.com\\\/de\\\/#organization\",\"name\":\"The MED-EL Blog\",\"url\":\"https:\\\/\\\/blog.medel.com\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/blog.medel.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/blog.medel.com\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/MED-EL_logo_L2.png\",\"contentUrl\":\"https:\\\/\\\/blog.medel.com\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/MED-EL_logo_L2.png\",\"width\":443,\"height\":200,\"caption\":\"The MED-EL Blog\"},\"image\":{\"@id\":\"https:\\\/\\\/blog.medel.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/blog.medel.com\\\/de\\\/#\\\/schema\\\/person\\\/9f8dcfb27ec87796d874e021602c56e2\",\"name\":\"MED-EL\",\"sameAs\":[\"https:\\\/\\\/www.medel.com\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Limpieza de tu procesador de audio: Gu\u00eda especial referente al COVID-19 (Coronavirus) - Blog MED-EL","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/blog.medel.com\/latam\/consejos-y-recomendaciones-latam\/para-adultos-latam\/limpieza-de-tu-procesador-de-audio-guia-especial-referente-al-covid-19-coronavirus\/","og_locale":"es_ES","og_type":"article","og_title":"Limpieza de tu procesador de audio: Gu\u00eda especial referente al COVID-19 (Coronavirus) - Blog MED-EL","og_description":"Durante estos tiempos sin precedentes, la Organizaci\u00f3n Mundial de la Salud (OMS) ha comunicado sus gu\u00edas sobre higiene para saber c\u00f3mo podemos protegernos a nosotros mismos y a los dem\u00e1s de ser infectados con el COVID-19. Esta informaci\u00f3n se puede encontrar aqu\u00ed. Limpieza de tu procesador de audio Antes de manipular el procesador de audio [&hellip;]","og_url":"https:\/\/blog.medel.com\/latam\/consejos-y-recomendaciones-latam\/para-adultos-latam\/limpieza-de-tu-procesador-de-audio-guia-especial-referente-al-covid-19-coronavirus\/","og_site_name":"The MED-EL Blog","article_published_time":"2020-04-17T20:34:57+00:00","article_modified_time":"2023-03-13T13:56:48+00:00","og_image":[{"width":800,"height":400,"url":"https:\/\/blog.medel.com\/wp-content\/uploads\/2023\/03\/cleaning-audio-processor-coronavirus-1-1.jpg","type":"image\/jpeg"}],"author":"MED-EL","twitter_card":"summary_large_image","twitter_misc":{"Written by":"MED-EL","Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/blog.medel.com\/latam\/consejos-y-recomendaciones-latam\/para-adultos-latam\/limpieza-de-tu-procesador-de-audio-guia-especial-referente-al-covid-19-coronavirus\/#article","isPartOf":{"@id":"https:\/\/blog.medel.com\/latam\/consejos-y-recomendaciones-latam\/para-adultos-latam\/limpieza-de-tu-procesador-de-audio-guia-especial-referente-al-covid-19-coronavirus\/"},"author":{"name":"MED-EL","@id":"https:\/\/blog.medel.com\/de\/#\/schema\/person\/9f8dcfb27ec87796d874e021602c56e2"},"headline":"Limpieza de tu procesador de audio: Gu\u00eda especial referente al COVID-19 (Coronavirus)","datePublished":"2020-04-17T20:34:57+00:00","dateModified":"2023-03-13T13:56:48+00:00","mainEntityOfPage":{"@id":"https:\/\/blog.medel.com\/latam\/consejos-y-recomendaciones-latam\/para-adultos-latam\/limpieza-de-tu-procesador-de-audio-guia-especial-referente-al-covid-19-coronavirus\/"},"wordCount":608,"commentCount":0,"publisher":{"@id":"https:\/\/blog.medel.com\/de\/#organization"},"image":{"@id":"https:\/\/blog.medel.com\/latam\/consejos-y-recomendaciones-latam\/para-adultos-latam\/limpieza-de-tu-procesador-de-audio-guia-especial-referente-al-covid-19-coronavirus\/#primaryimage"},"thumbnailUrl":"https:\/\/blog.medel.com\/wp-content\/uploads\/2023\/03\/cleaning-audio-processor-coronavirus-1-1.jpg","keywords":["COVID-19","Desinfecci\u00f3n","LImpieza"],"articleSection":["Para Adultos","Para Padres"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/blog.medel.com\/latam\/consejos-y-recomendaciones-latam\/para-adultos-latam\/limpieza-de-tu-procesador-de-audio-guia-especial-referente-al-covid-19-coronavirus\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/blog.medel.com\/latam\/consejos-y-recomendaciones-latam\/para-adultos-latam\/limpieza-de-tu-procesador-de-audio-guia-especial-referente-al-covid-19-coronavirus\/","url":"https:\/\/blog.medel.com\/latam\/consejos-y-recomendaciones-latam\/para-adultos-latam\/limpieza-de-tu-procesador-de-audio-guia-especial-referente-al-covid-19-coronavirus\/","name":"Limpieza de tu procesador de audio: Gu\u00eda especial referente al COVID-19 (Coronavirus) - Blog MED-EL","isPartOf":{"@id":"https:\/\/blog.medel.com\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/blog.medel.com\/latam\/consejos-y-recomendaciones-latam\/para-adultos-latam\/limpieza-de-tu-procesador-de-audio-guia-especial-referente-al-covid-19-coronavirus\/#primaryimage"},"image":{"@id":"https:\/\/blog.medel.com\/latam\/consejos-y-recomendaciones-latam\/para-adultos-latam\/limpieza-de-tu-procesador-de-audio-guia-especial-referente-al-covid-19-coronavirus\/#primaryimage"},"thumbnailUrl":"https:\/\/blog.medel.com\/wp-content\/uploads\/2023\/03\/cleaning-audio-processor-coronavirus-1-1.jpg","datePublished":"2020-04-17T20:34:57+00:00","dateModified":"2023-03-13T13:56:48+00:00","breadcrumb":{"@id":"https:\/\/blog.medel.com\/latam\/consejos-y-recomendaciones-latam\/para-adultos-latam\/limpieza-de-tu-procesador-de-audio-guia-especial-referente-al-covid-19-coronavirus\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/blog.medel.com\/latam\/consejos-y-recomendaciones-latam\/para-adultos-latam\/limpieza-de-tu-procesador-de-audio-guia-especial-referente-al-covid-19-coronavirus\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/blog.medel.com\/latam\/consejos-y-recomendaciones-latam\/para-adultos-latam\/limpieza-de-tu-procesador-de-audio-guia-especial-referente-al-covid-19-coronavirus\/#primaryimage","url":"https:\/\/blog.medel.com\/wp-content\/uploads\/2023\/03\/cleaning-audio-processor-coronavirus-1-1.jpg","contentUrl":"https:\/\/blog.medel.com\/wp-content\/uploads\/2023\/03\/cleaning-audio-processor-coronavirus-1-1.jpg","width":800,"height":400},{"@type":"BreadcrumbList","@id":"https:\/\/blog.medel.com\/latam\/consejos-y-recomendaciones-latam\/para-adultos-latam\/limpieza-de-tu-procesador-de-audio-guia-especial-referente-al-covid-19-coronavirus\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/blog.medel.com\/"},{"@type":"ListItem","position":2,"name":"Limpieza de tu procesador de audio: Gu\u00eda especial referente al COVID-19 (Coronavirus)"}]},{"@type":"WebSite","@id":"https:\/\/blog.medel.com\/de\/#website","url":"https:\/\/blog.medel.com\/de\/","name":"The MED-EL Blog","description":"","publisher":{"@id":"https:\/\/blog.medel.com\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/blog.medel.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/blog.medel.com\/de\/#organization","name":"The MED-EL Blog","url":"https:\/\/blog.medel.com\/de\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/blog.medel.com\/de\/#\/schema\/logo\/image\/","url":"https:\/\/blog.medel.com\/wp-content\/uploads\/2023\/02\/MED-EL_logo_L2.png","contentUrl":"https:\/\/blog.medel.com\/wp-content\/uploads\/2023\/02\/MED-EL_logo_L2.png","width":443,"height":200,"caption":"The MED-EL Blog"},"image":{"@id":"https:\/\/blog.medel.com\/de\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/blog.medel.com\/de\/#\/schema\/person\/9f8dcfb27ec87796d874e021602c56e2","name":"MED-EL","sameAs":["https:\/\/www.medel.com"]}]}},"_links":{"self":[{"href":"https:\/\/blog.medel.com\/latam\/wp-json\/wp\/v2\/posts\/53591","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.medel.com\/latam\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.medel.com\/latam\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.medel.com\/latam\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.medel.com\/latam\/wp-json\/wp\/v2\/comments?post=53591"}],"version-history":[{"count":1,"href":"https:\/\/blog.medel.com\/latam\/wp-json\/wp\/v2\/posts\/53591\/revisions"}],"predecessor-version":[{"id":53592,"href":"https:\/\/blog.medel.com\/latam\/wp-json\/wp\/v2\/posts\/53591\/revisions\/53592"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blog.medel.com\/latam\/wp-json\/wp\/v2\/media\/70732"}],"wp:attachment":[{"href":"https:\/\/blog.medel.com\/latam\/wp-json\/wp\/v2\/media?parent=53591"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.medel.com\/latam\/wp-json\/wp\/v2\/categories?post=53591"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.medel.com\/latam\/wp-json\/wp\/v2\/tags?post=53591"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}