{"id":53519,"date":"2019-06-04T18:23:16","date_gmt":"2019-06-04T18:23:16","guid":{"rendered":"https:\/\/blog.medel.com\/uncategorized-latam\/conoce-a-esteban-un-veterinario-con-implantes-cocleares\/"},"modified":"2023-03-13T13:54:20","modified_gmt":"2023-03-13T13:54:20","slug":"conoce-a-esteban-un-veterinario-con-implantes-cocleares","status":"publish","type":"post","link":"https:\/\/blog.medel.com\/latam\/historias-de-usuarios-latam\/conoce-a-esteban-un-veterinario-con-implantes-cocleares\/","title":{"rendered":"Conoce a Esteban, un veterinario con Implantes Cocleares"},"content":{"rendered":"<p>Esteban L\u00f3pez ha tenido p\u00e9rdida de audici\u00f3n desde que era beb\u00e9. Durante la escuela us\u00f3 aud\u00edfonos y sigui\u00f3 sus sue\u00f1os hasta la Facultad de Ciencias Veterinarias. Sin embargo, incluso con los aud\u00edfonos m\u00e1s potentes, tuvo dificultad para escuchar a las personas (\u00a1y a los animales!) claramente en el trabajo. Fue entonces cuando decidi\u00f3 implantarse. Ahora, su trabajo como veterinario es m\u00e1s f\u00e1cil que nunca, est\u00e1 aprendiendo un nuevo idioma e incluso tiene un mapa especial para escuchar su estetoscopio. Le pedimos que nos contara m\u00e1s sobre su camino a los implantes cocleares y sus planes para el futuro&#8230;<\/p>\n<hr \/>\n<p>&nbsp;<\/p>\n<p>Mi nombre es Esteban L\u00f3pez, tengo 45 a\u00f1os y soy argentino. Me gradu\u00e9 como m\u00e9dico veterinario en el a\u00f1o 2009 y trabajo junto a los animales desde entonces, eleg\u00ed la carrera porque amo a los animales, ellos fueron mis primeros amigos en la vida por fuera de la familia, con ellos no necesitaba hablar, s\u00f3lo jugar. Me gusta escuchar m\u00fasica de los a\u00f1os 80 y 90. Soy fan\u00e1tico de bandas como Queen, The Beatles, Roxette, IXNS y cantantes como Freddie Mercury, Aretha Franklin, Phil Collins, y Sting. Una de mis principales actividades para relajarme es ir al gimnasio.<\/p>\n<p>&nbsp;<\/p>\n<h3><strong>\u00bfPuedes contarnos acerca de tu p\u00e9rdida auditiva? \u00bfCu\u00e1ndo perdiste tu audici\u00f3n?<\/strong><\/h3>\n<p>Nac\u00ed con hipoacusia neurosensorial bilateral, de severa a profunda, de origen cong\u00e9nita viral: Rubeola. En su momento no exist\u00eda la tecnolog\u00eda para detectar la hipoacusia en los reci\u00e9n nacidos como s\u00ed existe en la actualidad, por lo que el diagn\u00f3stico lleg\u00f3 tarde, alrededor de los 3 a\u00f1os.<\/p>\n<p>&nbsp;<\/p>\n<h3><strong>\u00bfC\u00f3mo te afect\u00f3 m\u00e1s la p\u00e9rdida auditiva? \u00bfAfect\u00f3 tu trabajo como veterinario?<\/strong><\/h3>\n<p>Bueno, de muchas maneras, padec\u00ed del acoso escolar de los compa\u00f1eros, la indiferencia de los maestros, la desidia de los directores, pero por suerte pude terminar la escuela y luego la secundaria, en ambas fueron ambientes de personas oyentes. Mi primera dificultad como estudiante de Ciencias Veterinarias era con el uso de los estetoscopios comunes, ya que con la p\u00e9rdida que llevaba, me resultaba imposible percibir los sonidos card\u00edacos o pulmonares. Luego, ya recibido, encontr\u00e9 uno de casualidad en una casa de art\u00edculos m\u00e9dicos, uno electr\u00f3nico y antiguo, japon\u00e9s, que por sorpresa funciona bastante bien.<\/p>\n<p>&nbsp;<\/p>\n<h3><strong>\u00bfHubo un momento o experiencia espec\u00edfica que te hizo decidirte por un implante coclear?<\/strong><\/h3>\n<p>S\u00ed, hubo un momento en el que fui a un evento sobre soluciones auditivas y conoc\u00ed a muchas personas implantadas; qued\u00e9 sorprendido de lo bien que escuchaban y llevaban sus vidas con el implante coclear. De vuelta en mi ciudad, fui al consultorio de mi fonoaudi\u00f3loga, quien ya ven\u00eda insisti\u00e9ndome con que deb\u00eda implantarme, finalmente le di la raz\u00f3n y decid\u00ed hacerlo. Ella me recomend\u00f3 la marca MED-EL, esa misma noche, me sent\u00e9 frente a la computadora y busqu\u00e9 mediante Google todo lo relacionado a la marca. Qued\u00e9 fascinado con su historia y los avances hechos en la materia. Finalmente decid\u00ed implantarme con MED-EL y hoy en d\u00eda estoy muy contento.<\/p>\n<p>&nbsp;<\/p>\n<h3><strong>\u00bfC\u00f3mo fue la cirug\u00eda?<\/strong><\/h3>\n<p>Tuve dos cirug\u00edas en el a\u00f1o 2018, una en enero y la otra en septiembre. Ambas fueron un \u00e9xito, aunque duraron m\u00e1s de lo previsto debido a una posici\u00f3n an\u00f3mala de la c\u00f3clea y a lo peque\u00f1o que result\u00f3 la ventana redonda. De todas formas, el postoperatorio fue tranquilo, con descanso obligatorio en mi casa por 5 d\u00edas; a los 21 d\u00edas de la operaci\u00f3n se retiraban los puntos y finalmente a los 30 d\u00edas ocurr\u00eda el encendido.<\/p>\n<p>&nbsp;<\/p>\n<h3><strong>\u00bfQu\u00e9 pas\u00f3 en tu activaci\u00f3n? \u00bfC\u00f3mo te sentiste?<\/strong><\/h3>\n<p>La primera activaci\u00f3n fue en el o\u00eddo derecho y se sinti\u00f3 extra\u00f1a, ten\u00eda la expectativa de salir escuchando luego de encenderlo, pero no fue as\u00ed, llev\u00f3 un tiempo. En cambio, en la activaci\u00f3n del o\u00eddo izquierdo fue todo lo contrario, comenc\u00e9 a sentir sonidos y voces, todos iguales por unos d\u00edas, pero luego fue aclarando y comenc\u00e9 a distinguir las voces de los dem\u00e1s.<\/p>\n<p>&nbsp;<\/p>\n<h3><strong>\u00bfCu\u00e1l ha sido el cambio m\u00e1s grande desde la obtenci\u00f3n de un implante coclear?<\/strong><\/h3>\n<p>Los cambios m\u00e1s grandes han sido poder escuchar los sonidos con el o\u00eddo derecho, que estuvo en silencio durante muchos a\u00f1os y hablar por tel\u00e9fono por primera vez con los implantes tras 21 d\u00edas de implantarme el o\u00eddo izquierdo.<\/p>\n<p>&nbsp;<\/p>\n<h3><strong>\u00bfHa habido alg\u00fan desaf\u00edo desde la obtenci\u00f3n de un implante? \u00bfC\u00f3mo los superaste?<\/strong><\/h3>\n<p>S\u00ed, hubo un desaf\u00edo, actualmente estoy en el tercer a\u00f1o del idioma alem\u00e1n, y hubo un momento que dur\u00f3 un poquito m\u00e1s de un mes, cuando ya estaba operado del izquierdo y s\u00f3lo escuchaba con el implante derecho, me cost\u00f3 mucho distinguir las fon\u00e9ticas alemanas como las \u00e4, \u00f6 y las \u00fc. Igualmente mis compa\u00f1eros y mi profesora de alem\u00e1n colaboraron para que yo entendiera todo e incluso me escrib\u00edan en el pizarr\u00f3n las palabras que no entend\u00eda. Con los implantes espero poder terminar el curso de alem\u00e1n y as\u00ed poder romper mis propios l\u00edmites.<\/p>\n<p>&nbsp;<\/p>\n<h3><strong>\u00bfC\u00f3mo te han ayudado los implantes cocleares en el trabajo?<\/strong><\/h3>\n<p>Los implantes me ayudan much\u00edsimo, sobre todo en los ambientes ruidosos, ya que me permiten discriminar mejor las palabras e incluso hablar modulando mejor mi voz. ahora ya no hablo tan fuerte y nasal como antes, sino m\u00e1s bajo y con mucha m\u00e1s nitidez.<\/p>\n<p><strong>Tambi\u00e9n te puede interesar:<\/strong> <a href=\"\/?p=12112\" target=\"_blank\" rel=\"noopener noreferrer\">Tener \u00e9xito en el trabajo con p\u00e9rdida de la audici\u00f3n<\/a><\/p>\n<h3><strong>Nos dijo que tiene un mapa especial para su estetoscopio. \u00bfPuedes contarnos un poco m\u00e1s sobre esto?<\/strong><\/h3>\n<p>Si, con mi Fonoaudi\u00f3loga\u00a0hemos creado un mapa para usar exclusivamente con el estetoscopio electr\u00f3nico. B\u00e1sicamente es ajustar los electrodos de graves y agudos, ya que los sonidos card\u00edacos son fundamentalmente graves (los murmullos y soplos) con una porci\u00f3n muy ef\u00edmera de sonidos agudos (como los cierres valvulares). Para utilizarlo se necesita un ambiente muy tranquilo y silencioso, dado que cualquier ruido ambiental ser\u00e1 captado por el diafragma del estetoscopio.<\/p>\n<p>&nbsp;<\/p>\n<h3><strong>\u00bfCu\u00e1les son tus sonidos favoritos?<\/strong><\/h3>\n<p>Mis sonidos favoritos son el Tic-Tac del consultorio de mi fonoaudi\u00f3loga y disfrutar escuchando la m\u00fasica de los 80&#8217;s.<\/p>\n<p>&nbsp;<\/p>\n<p><em>Si quieres conocer m\u00e1s Historias de usuarios MED-EL como la de Esteban L\u00f3pez, haz clic <a href=\"\/?page_id=8175\" target=\"_blank\" rel=\"noopener noreferrer\">aqu\u00ed.<\/a><\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Esteban L\u00f3pez ha tenido p\u00e9rdida de audici\u00f3n desde que era beb\u00e9. Durante la escuela us\u00f3 aud\u00edfonos y sigui\u00f3 sus sue\u00f1os hasta la Facultad de Ciencias Veterinarias. Sin embargo, incluso con los aud\u00edfonos m\u00e1s potentes, tuvo dificultad para escuchar a las personas (\u00a1y a los animales!) claramente en el trabajo. Fue entonces cuando decidi\u00f3 implantarse. Ahora, [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":70426,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3361],"tags":[3385,3373,3386,3383,3387,3388],"class_list":["post-53519","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-historias-de-usuarios-latam","tag-argentina-latam","tag-hipoacusia-latam","tag-idiomas-latam","tag-perdida-auditiva-latam","tag-sordera-latam","tag-veterinario-latam"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Conoce a Esteban, un veterinario con Implantes Cocleares - Blog MED-EL<\/title>\n<meta name=\"description\" content=\"Esteban L\u00f3pez ha tenido p\u00e9rdida de audici\u00f3n desde que era beb\u00e9. Ahora, gracias a sus Implantes Cocleares ha podido cumplir su sue\u00f1o de ser veterinario.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/blog.medel.com\/latam\/historias-de-usuarios-latam\/conoce-a-esteban-un-veterinario-con-implantes-cocleares\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Conoce a Esteban, un veterinario con Implantes Cocleares - Blog MED-EL\" \/>\n<meta property=\"og:description\" content=\"Esteban L\u00f3pez ha tenido p\u00e9rdida de audici\u00f3n desde que era beb\u00e9. Ahora, gracias a sus Implantes Cocleares ha podido cumplir su sue\u00f1o de ser veterinario.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/blog.medel.com\/latam\/historias-de-usuarios-latam\/conoce-a-esteban-un-veterinario-con-implantes-cocleares\/\" \/>\n<meta property=\"og:site_name\" content=\"The MED-EL Blog\" \/>\n<meta property=\"article:published_time\" content=\"2019-06-04T18:23:16+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-03-13T13:54:20+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/blog.medel.com\/wp-content\/uploads\/2023\/03\/vet-with-cochlear-implants-2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2422\" \/>\n\t<meta property=\"og:image:height\" content=\"1211\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"MED-EL\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"MED-EL\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/blog.medel.com\\\/latam\\\/historias-de-usuarios-latam\\\/conoce-a-esteban-un-veterinario-con-implantes-cocleares\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blog.medel.com\\\/latam\\\/historias-de-usuarios-latam\\\/conoce-a-esteban-un-veterinario-con-implantes-cocleares\\\/\"},\"author\":{\"name\":\"MED-EL\",\"@id\":\"https:\\\/\\\/blog.medel.com\\\/#\\\/schema\\\/person\\\/9f8dcfb27ec87796d874e021602c56e2\"},\"headline\":\"Conoce a Esteban, un veterinario con Implantes Cocleares\",\"datePublished\":\"2019-06-04T18:23:16+00:00\",\"dateModified\":\"2023-03-13T13:54:20+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/blog.medel.com\\\/latam\\\/historias-de-usuarios-latam\\\/conoce-a-esteban-un-veterinario-con-implantes-cocleares\\\/\"},\"wordCount\":1115,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/blog.medel.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/blog.medel.com\\\/latam\\\/historias-de-usuarios-latam\\\/conoce-a-esteban-un-veterinario-con-implantes-cocleares\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/blog.medel.com\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/vet-with-cochlear-implants-2.jpg\",\"keywords\":[\"Argentina\",\"Hipoacusia\",\"idiomas\",\"P\u00e9rdida Auditiva\",\"sordera\",\"veterinario\"],\"articleSection\":[\"HISTORIAS DE USUARIOS\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/blog.medel.com\\\/latam\\\/historias-de-usuarios-latam\\\/conoce-a-esteban-un-veterinario-con-implantes-cocleares\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/blog.medel.com\\\/latam\\\/historias-de-usuarios-latam\\\/conoce-a-esteban-un-veterinario-con-implantes-cocleares\\\/\",\"url\":\"https:\\\/\\\/blog.medel.com\\\/latam\\\/historias-de-usuarios-latam\\\/conoce-a-esteban-un-veterinario-con-implantes-cocleares\\\/\",\"name\":\"Conoce a Esteban, un veterinario con Implantes Cocleares - Blog MED-EL\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blog.medel.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/blog.medel.com\\\/latam\\\/historias-de-usuarios-latam\\\/conoce-a-esteban-un-veterinario-con-implantes-cocleares\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/blog.medel.com\\\/latam\\\/historias-de-usuarios-latam\\\/conoce-a-esteban-un-veterinario-con-implantes-cocleares\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/blog.medel.com\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/vet-with-cochlear-implants-2.jpg\",\"datePublished\":\"2019-06-04T18:23:16+00:00\",\"dateModified\":\"2023-03-13T13:54:20+00:00\",\"description\":\"Esteban L\u00f3pez ha tenido p\u00e9rdida de audici\u00f3n desde que era beb\u00e9. Ahora, gracias a sus Implantes Cocleares ha podido cumplir su sue\u00f1o de ser veterinario.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/blog.medel.com\\\/latam\\\/historias-de-usuarios-latam\\\/conoce-a-esteban-un-veterinario-con-implantes-cocleares\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/blog.medel.com\\\/latam\\\/historias-de-usuarios-latam\\\/conoce-a-esteban-un-veterinario-con-implantes-cocleares\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/blog.medel.com\\\/latam\\\/historias-de-usuarios-latam\\\/conoce-a-esteban-un-veterinario-con-implantes-cocleares\\\/#primaryimage\",\"url\":\"https:\\\/\\\/blog.medel.com\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/vet-with-cochlear-implants-2.jpg\",\"contentUrl\":\"https:\\\/\\\/blog.medel.com\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/vet-with-cochlear-implants-2.jpg\",\"width\":2422,\"height\":1211},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/blog.medel.com\\\/latam\\\/historias-de-usuarios-latam\\\/conoce-a-esteban-un-veterinario-con-implantes-cocleares\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/blog.medel.com\\\/latam\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Conoce a Esteban, un veterinario con Implantes Cocleares\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/blog.medel.com\\\/#website\",\"url\":\"https:\\\/\\\/blog.medel.com\\\/\",\"name\":\"The MED-EL Blog\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/blog.medel.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/blog.medel.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/blog.medel.com\\\/#organization\",\"name\":\"The MED-EL Blog\",\"url\":\"https:\\\/\\\/blog.medel.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/blog.medel.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/blog.medel.com\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/MED-EL_logo_L2.png\",\"contentUrl\":\"https:\\\/\\\/blog.medel.com\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/MED-EL_logo_L2.png\",\"width\":443,\"height\":200,\"caption\":\"The MED-EL Blog\"},\"image\":{\"@id\":\"https:\\\/\\\/blog.medel.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/blog.medel.com\\\/#\\\/schema\\\/person\\\/9f8dcfb27ec87796d874e021602c56e2\",\"name\":\"MED-EL\",\"sameAs\":[\"https:\\\/\\\/www.medel.com\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Conoce a Esteban, un veterinario con Implantes Cocleares - Blog MED-EL","description":"Esteban L\u00f3pez ha tenido p\u00e9rdida de audici\u00f3n desde que era beb\u00e9. Ahora, gracias a sus Implantes Cocleares ha podido cumplir su sue\u00f1o de ser veterinario.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/blog.medel.com\/latam\/historias-de-usuarios-latam\/conoce-a-esteban-un-veterinario-con-implantes-cocleares\/","og_locale":"es_ES","og_type":"article","og_title":"Conoce a Esteban, un veterinario con Implantes Cocleares - Blog MED-EL","og_description":"Esteban L\u00f3pez ha tenido p\u00e9rdida de audici\u00f3n desde que era beb\u00e9. Ahora, gracias a sus Implantes Cocleares ha podido cumplir su sue\u00f1o de ser veterinario.","og_url":"https:\/\/blog.medel.com\/latam\/historias-de-usuarios-latam\/conoce-a-esteban-un-veterinario-con-implantes-cocleares\/","og_site_name":"The MED-EL Blog","article_published_time":"2019-06-04T18:23:16+00:00","article_modified_time":"2023-03-13T13:54:20+00:00","og_image":[{"width":2422,"height":1211,"url":"https:\/\/blog.medel.com\/wp-content\/uploads\/2023\/03\/vet-with-cochlear-implants-2.jpg","type":"image\/jpeg"}],"author":"MED-EL","twitter_card":"summary_large_image","twitter_misc":{"Written by":"MED-EL","Est. reading time":"6 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/blog.medel.com\/latam\/historias-de-usuarios-latam\/conoce-a-esteban-un-veterinario-con-implantes-cocleares\/#article","isPartOf":{"@id":"https:\/\/blog.medel.com\/latam\/historias-de-usuarios-latam\/conoce-a-esteban-un-veterinario-con-implantes-cocleares\/"},"author":{"name":"MED-EL","@id":"https:\/\/blog.medel.com\/#\/schema\/person\/9f8dcfb27ec87796d874e021602c56e2"},"headline":"Conoce a Esteban, un veterinario con Implantes Cocleares","datePublished":"2019-06-04T18:23:16+00:00","dateModified":"2023-03-13T13:54:20+00:00","mainEntityOfPage":{"@id":"https:\/\/blog.medel.com\/latam\/historias-de-usuarios-latam\/conoce-a-esteban-un-veterinario-con-implantes-cocleares\/"},"wordCount":1115,"commentCount":0,"publisher":{"@id":"https:\/\/blog.medel.com\/#organization"},"image":{"@id":"https:\/\/blog.medel.com\/latam\/historias-de-usuarios-latam\/conoce-a-esteban-un-veterinario-con-implantes-cocleares\/#primaryimage"},"thumbnailUrl":"https:\/\/blog.medel.com\/wp-content\/uploads\/2023\/03\/vet-with-cochlear-implants-2.jpg","keywords":["Argentina","Hipoacusia","idiomas","P\u00e9rdida Auditiva","sordera","veterinario"],"articleSection":["HISTORIAS DE USUARIOS"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/blog.medel.com\/latam\/historias-de-usuarios-latam\/conoce-a-esteban-un-veterinario-con-implantes-cocleares\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/blog.medel.com\/latam\/historias-de-usuarios-latam\/conoce-a-esteban-un-veterinario-con-implantes-cocleares\/","url":"https:\/\/blog.medel.com\/latam\/historias-de-usuarios-latam\/conoce-a-esteban-un-veterinario-con-implantes-cocleares\/","name":"Conoce a Esteban, un veterinario con Implantes Cocleares - Blog MED-EL","isPartOf":{"@id":"https:\/\/blog.medel.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/blog.medel.com\/latam\/historias-de-usuarios-latam\/conoce-a-esteban-un-veterinario-con-implantes-cocleares\/#primaryimage"},"image":{"@id":"https:\/\/blog.medel.com\/latam\/historias-de-usuarios-latam\/conoce-a-esteban-un-veterinario-con-implantes-cocleares\/#primaryimage"},"thumbnailUrl":"https:\/\/blog.medel.com\/wp-content\/uploads\/2023\/03\/vet-with-cochlear-implants-2.jpg","datePublished":"2019-06-04T18:23:16+00:00","dateModified":"2023-03-13T13:54:20+00:00","description":"Esteban L\u00f3pez ha tenido p\u00e9rdida de audici\u00f3n desde que era beb\u00e9. Ahora, gracias a sus Implantes Cocleares ha podido cumplir su sue\u00f1o de ser veterinario.","breadcrumb":{"@id":"https:\/\/blog.medel.com\/latam\/historias-de-usuarios-latam\/conoce-a-esteban-un-veterinario-con-implantes-cocleares\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/blog.medel.com\/latam\/historias-de-usuarios-latam\/conoce-a-esteban-un-veterinario-con-implantes-cocleares\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/blog.medel.com\/latam\/historias-de-usuarios-latam\/conoce-a-esteban-un-veterinario-con-implantes-cocleares\/#primaryimage","url":"https:\/\/blog.medel.com\/wp-content\/uploads\/2023\/03\/vet-with-cochlear-implants-2.jpg","contentUrl":"https:\/\/blog.medel.com\/wp-content\/uploads\/2023\/03\/vet-with-cochlear-implants-2.jpg","width":2422,"height":1211},{"@type":"BreadcrumbList","@id":"https:\/\/blog.medel.com\/latam\/historias-de-usuarios-latam\/conoce-a-esteban-un-veterinario-con-implantes-cocleares\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/blog.medel.com\/latam\/"},{"@type":"ListItem","position":2,"name":"Conoce a Esteban, un veterinario con Implantes Cocleares"}]},{"@type":"WebSite","@id":"https:\/\/blog.medel.com\/#website","url":"https:\/\/blog.medel.com\/","name":"The MED-EL Blog","description":"","publisher":{"@id":"https:\/\/blog.medel.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/blog.medel.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/blog.medel.com\/#organization","name":"The MED-EL Blog","url":"https:\/\/blog.medel.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/blog.medel.com\/#\/schema\/logo\/image\/","url":"https:\/\/blog.medel.com\/wp-content\/uploads\/2023\/02\/MED-EL_logo_L2.png","contentUrl":"https:\/\/blog.medel.com\/wp-content\/uploads\/2023\/02\/MED-EL_logo_L2.png","width":443,"height":200,"caption":"The MED-EL Blog"},"image":{"@id":"https:\/\/blog.medel.com\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/blog.medel.com\/#\/schema\/person\/9f8dcfb27ec87796d874e021602c56e2","name":"MED-EL","sameAs":["https:\/\/www.medel.com"]}]}},"_links":{"self":[{"href":"https:\/\/blog.medel.com\/latam\/wp-json\/wp\/v2\/posts\/53519","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.medel.com\/latam\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.medel.com\/latam\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.medel.com\/latam\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.medel.com\/latam\/wp-json\/wp\/v2\/comments?post=53519"}],"version-history":[{"count":1,"href":"https:\/\/blog.medel.com\/latam\/wp-json\/wp\/v2\/posts\/53519\/revisions"}],"predecessor-version":[{"id":53520,"href":"https:\/\/blog.medel.com\/latam\/wp-json\/wp\/v2\/posts\/53519\/revisions\/53520"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blog.medel.com\/latam\/wp-json\/wp\/v2\/media\/70426"}],"wp:attachment":[{"href":"https:\/\/blog.medel.com\/latam\/wp-json\/wp\/v2\/media?parent=53519"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.medel.com\/latam\/wp-json\/wp\/v2\/categories?post=53519"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.medel.com\/latam\/wp-json\/wp\/v2\/tags?post=53519"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}