{"id":53403,"date":"2018-07-30T15:14:05","date_gmt":"2018-07-30T15:14:05","guid":{"rendered":"https:\/\/blog.medel.com\/uncategorized-latam\/tocar-y-escuchar-musica-con-un-implante-coclear\/"},"modified":"2023-03-13T13:46:58","modified_gmt":"2023-03-13T13:46:58","slug":"tocar-y-escuchar-musica-con-un-implante-coclear","status":"publish","type":"post","link":"https:\/\/blog.medel.com\/latam\/consejos-y-recomendaciones-latam\/para-adultos-latam\/tocar-y-escuchar-musica-con-un-implante-coclear\/","title":{"rendered":"Tocar y escuchar m\u00fasica con un implante coclear"},"content":{"rendered":"<p>Muchos ejercicios de rehabilitaci\u00f3n se enfocan en el desarrollo del lenguaje, el habla y las habilidades de escucha. Estas son habilidades importantes para la comunicaci\u00f3n oral, pero hay mucho m\u00e1s para hacer con el sonido y la rehabilitaci\u00f3n.<\/p>\n<p><em><strong>Vincularse con la m\u00fasica o tocar un instrumento suma<\/strong><\/em>. Por un lado, ayuda con la construcci\u00f3n de algunas habilidades que se ense\u00f1an en rehabilitaci\u00f3n: entender el tono, el volumen y las duraciones; y, por otro lado, ayuda a desarrollar otras habilidades. Estas son algunas de las formas en las que la exposici\u00f3n a la m\u00fasica o tocar un instrumento ayudan a los usuarios de implantes cocleares.<\/p>\n<h3><strong>LA M\u00daSICA CONSTRUYE HABILIDADES DE ESCUCHA<\/strong><\/h3>\n<p>La m\u00fasica es sonido puro, y la exposici\u00f3n al sonido ayuda a construir habilidades de escucha. La construcci\u00f3n de habilidades de escucha con m\u00fasica puede hacerse con todo tipo de actividades musicales. Cantar canciones, escuchar m\u00fasica grabada o tocar un instrumento son diferentes maneras de construir habilidades de escucha.<\/p>\n<p><em><strong>Cuando escuchamos m\u00fasica, le ense\u00f1amos a nuestro cerebro a prestar atenci\u00f3n e identificar diferentes aspectos de la m\u00fasica<\/strong><\/em>: por ejemplo, las palabras que se est\u00e1n cantando, la melod\u00eda de una canci\u00f3n, o c\u00f3mo un instrumento cambia de tono.<\/p>\n<p>La m\u00fasica tambi\u00e9n construye habilidades de creaci\u00f3n de secuencias: como una pieza musical se toca en un orden espec\u00edfico, la repetici\u00f3n nos ayuda a predecir qu\u00e9 suceder\u00e1 a continuaci\u00f3n en una pieza. Y para los ni\u00f1os que est\u00e1n aprendiendo el lenguaje y desarrollando sus habilidades cognitivas, esta creaci\u00f3n de secuencias les ayuda a desarrollar conceptos como \u00abantes\u00bb, \u00abdurante\u00bb y \u00abdespu\u00e9s\u00bb.<\/p>\n<h3><strong>LA M\u00daSICA CONSTRUYE HABILIDADES SOCIALES<\/strong><\/h3>\n<p>Incluso m\u00e1s que eso, la m\u00fasica ayuda a construir habilidades de desarrollo y sociales. Escuchar y hablar de m\u00fasica con otros estimula la comunicaci\u00f3n y las habilidades de pensamiento cognitivo.<\/p>\n<p>Participar en grupos musicales como una banda o una orquesta construye habilidades sociales y emocionales: <strong><em>hacer amigos e interactuar con otras personas<\/em><\/strong>. Para los ni\u00f1os, tocar juntos en un grupo musical les puede ense\u00f1ar a compartir, tomar turnos y cooperar con otros. La misma acci\u00f3n de tocar un instrumento o llevar a cabo acciones a lo largo de canciones tambi\u00e9n hace interactuar diferentes sentidos como la vista, el tacto y el o\u00eddo, mientras construye las habilidades motoras y la coordinaci\u00f3n mano-ojo.<\/p>\n<h4><span style=\"font-size: 24px;\"><strong>Elegir m\u00fasica para escuchar o un instrumento<\/strong><\/span><\/h4>\n<p>Cuando elijas m\u00fasica para escuchar, usa tus preferencias personales.<\/p>\n<p><strong><em>Los destinatarios de implantes cocleares adultos deber\u00edan elegir m\u00fasica que puedan disfrutar<\/em><\/strong>. Puede haber canciones o piezas en particular que encuentras m\u00e1s f\u00e1ciles de escuchar, como las que tienen un ritmo simple o letras que ya conoces. Es buena idea comenzar con estas antes de pasar a piezas musicales m\u00e1s complejas, como las sinfon\u00edas.<\/p>\n<p>Si est\u00e1s ayudando a tu ni\u00f1o a escuchar m\u00fasica, elije las canciones que son para su rango de edad. Y recuerda, la repetici\u00f3n ayuda mucho en el desarrollo de habilidades de escucha y del lenguaje, as\u00ed que no tengas miedo de cantar o reproducir la misma canci\u00f3n una y otra vez. Lo m\u00e1s importante es que <strong><em>t\u00fa y tu hijo disfruten la m\u00fasica que est\u00e1n escuchando<\/em><\/strong>, as\u00ed que \u00a1mueve tu cuerpo, d\u00e9jate llevar por el ritmo y la letra, y dale vida a la canci\u00f3n!<\/p>\n<p>Si est\u00e1s pensando en empezar a tocar un instrumento, la pregunta es cu\u00e1l.<\/p>\n<p>Cuando elijas qu\u00e9 instrumento quieres tocar, nuevamente la mayor consideraci\u00f3n es qu\u00e9 te interesa a ti. \u00bfTe gusta el sonido de los instrumentos de metal como la trompeta? \u00bfO prefieres el estilo delicado de un saxof\u00f3n tocando jazz? \u00bfTal vez el rango de armon\u00edas del piano?<\/p>\n<p>No hay un instrumento errado para tocar, y <strong><em>los destinatarios de MED-EL tocan todo tipo de instrumentos<\/em><\/strong>. Solo elije el que m\u00e1s te interesa a ti, y date tiempo para practicar y aprender. En resumen, comprom\u00e9tete.<\/p>\n<p>Si no tienes una preferencia, el piano o el teclado pueden ser buenos para comenzar. Esto es porque es bastante directo: tocas una tecla y tienes una \u00fanica nota espec\u00edfica.<\/p>\n<h4><span style=\"font-size: 20px;\"><strong>Consejos para tocar m\u00fasica<\/strong><\/span><\/h4>\n<p>Una vez que has empezado a escuchar o tocar m\u00fasica, \u00bfcu\u00e1l es la mejor manera de practicar? Aqu\u00ed tienes algunos consejos:<\/p>\n<p><strong>&#8211; <em>Practica todos los d\u00edas<\/em><\/strong>. Cuanto m\u00e1s practiques, m\u00e1s experiencias positivas tendr\u00e1s.<br \/>\n<strong><em>&#8211; Elige m\u00fasica que disfrutes<\/em><\/strong>. Otras personas pueden sugerirte m\u00fasica, pero no hay raz\u00f3n para seguir tocando una canci\u00f3n si no te hace feliz.<br \/>\n<em><strong>&#8211; Observa a otras personas ejecutando m\u00fasica y escucha m\u00fasica en situaciones que disfrutes.<\/strong><\/em> Ve a conciertos, o mira actuaciones online.<\/p>\n<p><iframe loading=\"lazy\" src=\"https:\/\/www.youtube.com\/embed\/D2Ak9iTTTr8\" width=\"560\" height=\"315\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/p>\n<p><em>Esta publicaci\u00f3n fue escrita con la ayuda de Janani Jeyaraman, una especialista de rehabilitaci\u00f3n de MED-EL. Subscr\u00edbete al blog de <a href=\"\/?page_id=8189\">MED-EL Latinoam\u00e9rica<\/a> para recibir m\u00e1s consejos pr\u00e1cticos sobre m\u00fasica, rehabilitaci\u00f3n y m\u00e1s.<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Muchos ejercicios de rehabilitaci\u00f3n se enfocan en el desarrollo del lenguaje, el habla y las habilidades de escucha. Estas son habilidades importantes para la comunicaci\u00f3n oral, pero hay mucho m\u00e1s para hacer con el sonido y la rehabilitaci\u00f3n. Vincularse con la m\u00fasica o tocar un instrumento suma. Por un lado, ayuda con la construcci\u00f3n de [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":69850,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3356],"tags":[3373,3443,3404,3459,3383,3368],"class_list":["post-53403","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-para-adultos-latam","tag-hipoacusia-latam","tag-med-el-latam","tag-med-el-latinoamerica-latam","tag-musica-con-ic-latam","tag-perdida-auditiva-latam","tag-soluciones-auditivas-latam"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Tocar y escuchar m\u00fasica con un implante coclear - The MED-EL Blog<\/title>\n<meta name=\"description\" content=\"La m\u00fasica es sonido puro, y la exposici\u00f3n al sonido ayuda a construir habilidades de escucha. La construcci\u00f3n de habilidades de escucha con m\u00fasica puede hacerse con todo tipo de actividades musicales.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/blog.medel.com\/latam\/consejos-y-recomendaciones-latam\/para-adultos-latam\/tocar-y-escuchar-musica-con-un-implante-coclear\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Tocar y escuchar m\u00fasica con un implante coclear - The MED-EL Blog\" \/>\n<meta property=\"og:description\" content=\"La m\u00fasica es sonido puro, y la exposici\u00f3n al sonido ayuda a construir habilidades de escucha. La construcci\u00f3n de habilidades de escucha con m\u00fasica puede hacerse con todo tipo de actividades musicales.\" \/>\n<meta property=\"og:url\" content=\"http:\/\/blog.medel.com\/latam\/consejos-y-recomendaciones-latam\/para-adultos-latam\/tocar-y-escuchar-musica-con-un-implante-coclear\/\" \/>\n<meta property=\"og:site_name\" content=\"The MED-EL Blog\" \/>\n<meta property=\"article:published_time\" content=\"2018-07-30T15:14:05+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-03-13T13:46:58+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/blog.medel.com\/wp-content\/uploads\/2023\/03\/img_0352-1-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"853\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"MED-EL\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"MED-EL\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"http:\\\/\\\/blog.medel.com\\\/latam\\\/consejos-y-recomendaciones-latam\\\/para-adultos-latam\\\/tocar-y-escuchar-musica-con-un-implante-coclear\\\/#article\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/blog.medel.com\\\/latam\\\/consejos-y-recomendaciones-latam\\\/para-adultos-latam\\\/tocar-y-escuchar-musica-con-un-implante-coclear\\\/\"},\"author\":{\"name\":\"MED-EL\",\"@id\":\"https:\\\/\\\/blog.medel.com\\\/de\\\/#\\\/schema\\\/person\\\/9f8dcfb27ec87796d874e021602c56e2\"},\"headline\":\"Tocar y escuchar m\u00fasica con un implante coclear\",\"datePublished\":\"2018-07-30T15:14:05+00:00\",\"dateModified\":\"2023-03-13T13:46:58+00:00\",\"mainEntityOfPage\":{\"@id\":\"http:\\\/\\\/blog.medel.com\\\/latam\\\/consejos-y-recomendaciones-latam\\\/para-adultos-latam\\\/tocar-y-escuchar-musica-con-un-implante-coclear\\\/\"},\"wordCount\":869,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/blog.medel.com\\\/de\\\/#organization\"},\"image\":{\"@id\":\"http:\\\/\\\/blog.medel.com\\\/latam\\\/consejos-y-recomendaciones-latam\\\/para-adultos-latam\\\/tocar-y-escuchar-musica-con-un-implante-coclear\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/blog.medel.com\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/img_0352-1-1.jpg\",\"keywords\":[\"Hipoacusia\",\"MED-EL\",\"MED-EL Latinoam\u00e9rica\",\"M\u00fasica con IC\",\"P\u00e9rdida Auditiva\",\"Soluciones Auditivas\"],\"articleSection\":[\"Para Adultos\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"http:\\\/\\\/blog.medel.com\\\/latam\\\/consejos-y-recomendaciones-latam\\\/para-adultos-latam\\\/tocar-y-escuchar-musica-con-un-implante-coclear\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/blog.medel.com\\\/latam\\\/consejos-y-recomendaciones-latam\\\/para-adultos-latam\\\/tocar-y-escuchar-musica-con-un-implante-coclear\\\/\",\"url\":\"http:\\\/\\\/blog.medel.com\\\/latam\\\/consejos-y-recomendaciones-latam\\\/para-adultos-latam\\\/tocar-y-escuchar-musica-con-un-implante-coclear\\\/\",\"name\":\"Tocar y escuchar m\u00fasica con un implante coclear - The MED-EL Blog\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blog.medel.com\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"http:\\\/\\\/blog.medel.com\\\/latam\\\/consejos-y-recomendaciones-latam\\\/para-adultos-latam\\\/tocar-y-escuchar-musica-con-un-implante-coclear\\\/#primaryimage\"},\"image\":{\"@id\":\"http:\\\/\\\/blog.medel.com\\\/latam\\\/consejos-y-recomendaciones-latam\\\/para-adultos-latam\\\/tocar-y-escuchar-musica-con-un-implante-coclear\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/blog.medel.com\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/img_0352-1-1.jpg\",\"datePublished\":\"2018-07-30T15:14:05+00:00\",\"dateModified\":\"2023-03-13T13:46:58+00:00\",\"description\":\"La m\u00fasica es sonido puro, y la exposici\u00f3n al sonido ayuda a construir habilidades de escucha. La construcci\u00f3n de habilidades de escucha con m\u00fasica puede hacerse con todo tipo de actividades musicales.\",\"breadcrumb\":{\"@id\":\"http:\\\/\\\/blog.medel.com\\\/latam\\\/consejos-y-recomendaciones-latam\\\/para-adultos-latam\\\/tocar-y-escuchar-musica-con-un-implante-coclear\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\\\/\\\/blog.medel.com\\\/latam\\\/consejos-y-recomendaciones-latam\\\/para-adultos-latam\\\/tocar-y-escuchar-musica-con-un-implante-coclear\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"http:\\\/\\\/blog.medel.com\\\/latam\\\/consejos-y-recomendaciones-latam\\\/para-adultos-latam\\\/tocar-y-escuchar-musica-con-un-implante-coclear\\\/#primaryimage\",\"url\":\"https:\\\/\\\/blog.medel.com\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/img_0352-1-1.jpg\",\"contentUrl\":\"https:\\\/\\\/blog.medel.com\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/img_0352-1-1.jpg\",\"width\":1280,\"height\":853},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\\\/\\\/blog.medel.com\\\/latam\\\/consejos-y-recomendaciones-latam\\\/para-adultos-latam\\\/tocar-y-escuchar-musica-con-un-implante-coclear\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/blog.medel.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tocar y escuchar m\u00fasica con un implante coclear\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/blog.medel.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/blog.medel.com\\\/de\\\/\",\"name\":\"The MED-EL Blog\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/blog.medel.com\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/blog.medel.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/blog.medel.com\\\/de\\\/#organization\",\"name\":\"The MED-EL Blog\",\"url\":\"https:\\\/\\\/blog.medel.com\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/blog.medel.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/blog.medel.com\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/MED-EL_logo_L2.png\",\"contentUrl\":\"https:\\\/\\\/blog.medel.com\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/MED-EL_logo_L2.png\",\"width\":443,\"height\":200,\"caption\":\"The MED-EL Blog\"},\"image\":{\"@id\":\"https:\\\/\\\/blog.medel.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/blog.medel.com\\\/de\\\/#\\\/schema\\\/person\\\/9f8dcfb27ec87796d874e021602c56e2\",\"name\":\"MED-EL\",\"sameAs\":[\"https:\\\/\\\/www.medel.com\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Tocar y escuchar m\u00fasica con un implante coclear - The MED-EL Blog","description":"La m\u00fasica es sonido puro, y la exposici\u00f3n al sonido ayuda a construir habilidades de escucha. La construcci\u00f3n de habilidades de escucha con m\u00fasica puede hacerse con todo tipo de actividades musicales.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/blog.medel.com\/latam\/consejos-y-recomendaciones-latam\/para-adultos-latam\/tocar-y-escuchar-musica-con-un-implante-coclear\/","og_locale":"es_ES","og_type":"article","og_title":"Tocar y escuchar m\u00fasica con un implante coclear - The MED-EL Blog","og_description":"La m\u00fasica es sonido puro, y la exposici\u00f3n al sonido ayuda a construir habilidades de escucha. La construcci\u00f3n de habilidades de escucha con m\u00fasica puede hacerse con todo tipo de actividades musicales.","og_url":"http:\/\/blog.medel.com\/latam\/consejos-y-recomendaciones-latam\/para-adultos-latam\/tocar-y-escuchar-musica-con-un-implante-coclear\/","og_site_name":"The MED-EL Blog","article_published_time":"2018-07-30T15:14:05+00:00","article_modified_time":"2023-03-13T13:46:58+00:00","og_image":[{"width":1280,"height":853,"url":"http:\/\/blog.medel.com\/wp-content\/uploads\/2023\/03\/img_0352-1-1.jpg","type":"image\/jpeg"}],"author":"MED-EL","twitter_card":"summary_large_image","twitter_misc":{"Written by":"MED-EL","Est. reading time":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"http:\/\/blog.medel.com\/latam\/consejos-y-recomendaciones-latam\/para-adultos-latam\/tocar-y-escuchar-musica-con-un-implante-coclear\/#article","isPartOf":{"@id":"http:\/\/blog.medel.com\/latam\/consejos-y-recomendaciones-latam\/para-adultos-latam\/tocar-y-escuchar-musica-con-un-implante-coclear\/"},"author":{"name":"MED-EL","@id":"https:\/\/blog.medel.com\/de\/#\/schema\/person\/9f8dcfb27ec87796d874e021602c56e2"},"headline":"Tocar y escuchar m\u00fasica con un implante coclear","datePublished":"2018-07-30T15:14:05+00:00","dateModified":"2023-03-13T13:46:58+00:00","mainEntityOfPage":{"@id":"http:\/\/blog.medel.com\/latam\/consejos-y-recomendaciones-latam\/para-adultos-latam\/tocar-y-escuchar-musica-con-un-implante-coclear\/"},"wordCount":869,"commentCount":0,"publisher":{"@id":"https:\/\/blog.medel.com\/de\/#organization"},"image":{"@id":"http:\/\/blog.medel.com\/latam\/consejos-y-recomendaciones-latam\/para-adultos-latam\/tocar-y-escuchar-musica-con-un-implante-coclear\/#primaryimage"},"thumbnailUrl":"https:\/\/blog.medel.com\/wp-content\/uploads\/2023\/03\/img_0352-1-1.jpg","keywords":["Hipoacusia","MED-EL","MED-EL Latinoam\u00e9rica","M\u00fasica con IC","P\u00e9rdida Auditiva","Soluciones Auditivas"],"articleSection":["Para Adultos"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["http:\/\/blog.medel.com\/latam\/consejos-y-recomendaciones-latam\/para-adultos-latam\/tocar-y-escuchar-musica-con-un-implante-coclear\/#respond"]}]},{"@type":"WebPage","@id":"http:\/\/blog.medel.com\/latam\/consejos-y-recomendaciones-latam\/para-adultos-latam\/tocar-y-escuchar-musica-con-un-implante-coclear\/","url":"http:\/\/blog.medel.com\/latam\/consejos-y-recomendaciones-latam\/para-adultos-latam\/tocar-y-escuchar-musica-con-un-implante-coclear\/","name":"Tocar y escuchar m\u00fasica con un implante coclear - The MED-EL Blog","isPartOf":{"@id":"https:\/\/blog.medel.com\/de\/#website"},"primaryImageOfPage":{"@id":"http:\/\/blog.medel.com\/latam\/consejos-y-recomendaciones-latam\/para-adultos-latam\/tocar-y-escuchar-musica-con-un-implante-coclear\/#primaryimage"},"image":{"@id":"http:\/\/blog.medel.com\/latam\/consejos-y-recomendaciones-latam\/para-adultos-latam\/tocar-y-escuchar-musica-con-un-implante-coclear\/#primaryimage"},"thumbnailUrl":"https:\/\/blog.medel.com\/wp-content\/uploads\/2023\/03\/img_0352-1-1.jpg","datePublished":"2018-07-30T15:14:05+00:00","dateModified":"2023-03-13T13:46:58+00:00","description":"La m\u00fasica es sonido puro, y la exposici\u00f3n al sonido ayuda a construir habilidades de escucha. La construcci\u00f3n de habilidades de escucha con m\u00fasica puede hacerse con todo tipo de actividades musicales.","breadcrumb":{"@id":"http:\/\/blog.medel.com\/latam\/consejos-y-recomendaciones-latam\/para-adultos-latam\/tocar-y-escuchar-musica-con-un-implante-coclear\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["http:\/\/blog.medel.com\/latam\/consejos-y-recomendaciones-latam\/para-adultos-latam\/tocar-y-escuchar-musica-con-un-implante-coclear\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"http:\/\/blog.medel.com\/latam\/consejos-y-recomendaciones-latam\/para-adultos-latam\/tocar-y-escuchar-musica-con-un-implante-coclear\/#primaryimage","url":"https:\/\/blog.medel.com\/wp-content\/uploads\/2023\/03\/img_0352-1-1.jpg","contentUrl":"https:\/\/blog.medel.com\/wp-content\/uploads\/2023\/03\/img_0352-1-1.jpg","width":1280,"height":853},{"@type":"BreadcrumbList","@id":"http:\/\/blog.medel.com\/latam\/consejos-y-recomendaciones-latam\/para-adultos-latam\/tocar-y-escuchar-musica-con-un-implante-coclear\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/blog.medel.com\/"},{"@type":"ListItem","position":2,"name":"Tocar y escuchar m\u00fasica con un implante coclear"}]},{"@type":"WebSite","@id":"https:\/\/blog.medel.com\/de\/#website","url":"https:\/\/blog.medel.com\/de\/","name":"The MED-EL Blog","description":"","publisher":{"@id":"https:\/\/blog.medel.com\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/blog.medel.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/blog.medel.com\/de\/#organization","name":"The MED-EL Blog","url":"https:\/\/blog.medel.com\/de\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/blog.medel.com\/de\/#\/schema\/logo\/image\/","url":"https:\/\/blog.medel.com\/wp-content\/uploads\/2023\/02\/MED-EL_logo_L2.png","contentUrl":"https:\/\/blog.medel.com\/wp-content\/uploads\/2023\/02\/MED-EL_logo_L2.png","width":443,"height":200,"caption":"The MED-EL Blog"},"image":{"@id":"https:\/\/blog.medel.com\/de\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/blog.medel.com\/de\/#\/schema\/person\/9f8dcfb27ec87796d874e021602c56e2","name":"MED-EL","sameAs":["https:\/\/www.medel.com"]}]}},"_links":{"self":[{"href":"https:\/\/blog.medel.com\/latam\/wp-json\/wp\/v2\/posts\/53403","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.medel.com\/latam\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.medel.com\/latam\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.medel.com\/latam\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.medel.com\/latam\/wp-json\/wp\/v2\/comments?post=53403"}],"version-history":[{"count":1,"href":"https:\/\/blog.medel.com\/latam\/wp-json\/wp\/v2\/posts\/53403\/revisions"}],"predecessor-version":[{"id":53404,"href":"https:\/\/blog.medel.com\/latam\/wp-json\/wp\/v2\/posts\/53403\/revisions\/53404"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blog.medel.com\/latam\/wp-json\/wp\/v2\/media\/69850"}],"wp:attachment":[{"href":"https:\/\/blog.medel.com\/latam\/wp-json\/wp\/v2\/media?parent=53403"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.medel.com\/latam\/wp-json\/wp\/v2\/categories?post=53403"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.medel.com\/latam\/wp-json\/wp\/v2\/tags?post=53403"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}