{"id":53381,"date":"2018-05-09T20:02:08","date_gmt":"2018-05-09T20:02:08","guid":{"rendered":"https:\/\/blog.medel.com\/uncategorized-latam\/los-implantes-cocleares-y-la-seguridad-en-resonancias-magneticas\/"},"modified":"2023-03-13T13:46:25","modified_gmt":"2023-03-13T13:46:25","slug":"los-implantes-cocleares-y-la-seguridad-en-resonancias-magneticas","status":"publish","type":"post","link":"https:\/\/blog.medel.com\/latam\/tecnologia-latam\/los-implantes-cocleares-y-la-seguridad-en-resonancias-magneticas\/","title":{"rendered":"Los implantes cocleares y la seguridad en resonancias magn\u00e9ticas (RMN): \u00bfQu\u00e9 significa esto en realidad?"},"content":{"rendered":"<p>En las oficinas centrales de MED-EL, en Austria, conectamos las mentes m\u00e1s brillantes del mundo para crear el futuro de la tecnolog\u00eda en implantes auditivos. En la primera de una serie de publicaciones de invitados, les presentaremos a expertos cient\u00edficos, investigadores e ingenieros de todo el planeta que est\u00e1n trabajando para llevar audici\u00f3n al mundo.<\/p>\n<p><em><strong>\u00bfCu\u00e1l es la relaci\u00f3n entre las <a href=\"http:\/\/www.medel.com\/esl\/cochlear-implants-mri-safety\/\" target=\"_blank\" rel=\"noopener\">resonancias magn\u00e9ticas<\/a> y los IC?<\/strong> <\/em>Lo que necesita es leer esta entrevista con Ellyce, ingeniera en resonancias de MED-EL, que comparte su experiencia desde Nueva Zelanda. Ellyce se sent\u00f3 con nosotros para compartir un poco sobre lo que hace su equipo de resonancia magn\u00e9tica y sobre por qu\u00e9 la seguridad en las resonancias es tan importante para los usuarios de implantes cocleares.<\/p>\n<h3><strong>\u00a1GRACIAS POR CONVERSAR CON NOSOTROS, ELLYCE! \u00bfPUEDES CONTARNOS UN POCO SOBRE TI?<\/strong><\/h3>\n<p>Nac\u00ed en Gisborne, una peque\u00f1a ciudad en la costa este de Nueva Zelanda. Primero estudi\u00e9 la carrera de grado de Ingenier\u00eda en la Universidad de Auckland y luego hice un doctorado en Ingenier\u00eda Biom\u00e9dica en el Instituto de Bioingenier\u00eda de Auckland.<\/p>\n<p>Mi trabajo diario es una <em><strong>mezcla de pruebas f\u00edsicas en un laboratorio o una cl\u00ednica y simulaciones en computadora<\/strong><\/em>. Las simulaciones replican el ambiente de la RMN para predecir c\u00f3mo los nuevos implantes o caracter\u00edsticas pueden afectar la seguridad del paciente.<\/p>\n<h3><strong><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-9507 size-large\" src=\"https:\/\/blog.medel.com\/wp-content\/uploads\/2018\/05\/ic_seguridad_resonancias_2-1024x573.jpg\" alt=\"\" width=\"1024\" height=\"573\" \/>\u00bfQU\u00c9 ENCUENTRAS INTERESANTE DE TRABAJAR CON IC Y RMN?<\/strong><\/h3>\n<p>Tanto las tecnolog\u00edas de implantes como las de im\u00e1genes m\u00e9dicas est\u00e1n mejorando r\u00e1pidamente, con lo cual m\u00e1s personas est\u00e1n recibiendo implantes cocleares y se est\u00e1n haciendo RMN. Por eso, estas ramas de la tecnolog\u00eda m\u00e9dica tienen que trabajar en conjunto para asegurar la seguridad del paciente. A medida que el uso de las RMN aumenta, es importante que no se excluya a pacientes que tienen un implante.<\/p>\n<h3><strong>TODO ESTO DE LA TECNOLOG\u00cdA DE IC Y LAS RMN PUEDE VOLVERSE BASTANTE CONFUSO PARA LOS QUE NO SABEN DEL TEMA. \u00bfPUEDES EXPLICAR BREVEMENTE POR QU\u00c9 MED-EL VALORA TANTO LA SEGURIDAD EN RMN?<\/strong><\/h3>\n<p>La calificaci\u00f3n Tesla de una RMN representa la fuerza del campo magn\u00e9tico est\u00e1tico. Durante una RMN, el campo magn\u00e9tico est\u00e1 siempre presente. <a href=\"http:\/\/www.medel.com\/esl\/synchrony-faq\/\" target=\"_blank\" rel=\"noopener\">SYNCHRONY<\/a> tiene un im\u00e1n rotatorio dentro del implante coclear que evita que el implante gire y se mueva en direcci\u00f3n al im\u00e1n.<\/p>\n<p>El im\u00e1n del implante coclear SYNCHRONY tambi\u00e9n permite olvidarte de las citas con el cirujano para retirar el im\u00e1n del implante antes de una RMN, incluso con las de clasificaci\u00f3n Tesla 3.0. Esto es particularmente importante ya que, en ocasiones, las RMN se necesitan r\u00e1pida e inesperadamente.<\/p>\n<p>Por ejemplo, despu\u00e9s de una lesi\u00f3n o un accidente. Cada vez se usan m\u00e1s las RMN, ya que durante este estudio el paciente no es expuesto a la radiaci\u00f3n de los rayos X o de las tomograf\u00edas computadas, y adem\u00e1s proporcionan im\u00e1genes de un espectro m\u00e1s amplio de tejidos del cuerpo. Por eso <em><strong>es importante que los pacientes puedan hacerse RMN de clasificaci\u00f3n Tesla 1.5 y 3.0 sin la necesidad de una cirug\u00eda<\/strong><\/em>.<\/p>\n<h3><strong>\u00bfCU\u00c1LES FUERON LOS DESARROLLOS M\u00c1S IMPORTANTES EN CUANTO A SEGURIDAD EN RMN EN LOS \u00daLTIMOS A\u00d1OS?<\/strong><\/h3>\n<p>Hasta hace muy poco, cualquier paciente que tuviera un implante era inmediatamente rechazado para una RMN por el riesgo que el implante interactuara con los campos electromagn\u00e9ticos. Sin embargo, al entender mejor a las m\u00e1quinas de RMN y al mejorar los dise\u00f1os de implantes, como el del SYNCHRONY en 2014, es posible hacer pruebas s\u00f3lidas y demostraciones de RMN seguras con implantes colocados.<\/p>\n<p>La investigaci\u00f3n en m\u00e1quinas de RMN m\u00e1s potentes y complejas est\u00e1 muy activa, y ans\u00edo el desaf\u00edo de estar a la par de estas innovaciones para asegurar que nuestros pacientes tengan acceso a ellas cada vez que entran en la cl\u00ednica.<\/p>\n<p><em>\u00a1Gracias, Ellyce!<\/em><\/p>\n<p><iframe loading=\"lazy\" src=\"https:\/\/www.youtube.com\/embed\/UfuKmsJCClE\" width=\"560\" height=\"315\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/p>\n<p>\u00bfTienes preguntas sobre implantes cocleares y RMN? \u00bfO te has hecho una RMN con tu implante coclear? \u00a1Comenta m\u00e1s abajo!<\/p>\n<p><em>\u00bfTe gust\u00f3 esta publicaci\u00f3n sobre seguridad en RMN e implantes cocleares? <a href=\"\/?page_id=8189\">Subscr\u00edbete al Blog de MED-EL Latinoam\u00e9rica<\/a> ingresando tu e-mail a continuaci\u00f3n para recibir las \u00faltimas historias de nuestros visitantes, publicaciones sobre tecnolog\u00eda, consejos y trucos.<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>En las oficinas centrales de MED-EL, en Austria, conectamos las mentes m\u00e1s brillantes del mundo para crear el futuro de la tecnolog\u00eda en implantes auditivos. En la primera de una serie de publicaciones de invitados, les presentaremos a expertos cient\u00edficos, investigadores e ingenieros de todo el planeta que est\u00e1n trabajando para llevar audici\u00f3n al mundo. [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":69751,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3362],"tags":[3443,3404,3383,3368],"class_list":["post-53381","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-tecnologia-latam","tag-med-el-latam","tag-med-el-latinoamerica-latam","tag-perdida-auditiva-latam","tag-soluciones-auditivas-latam"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Los implantes cocleares y la seguridad en resonancias magn\u00e9ticas (RMN): \u00bfQu\u00e9 significa esto en realidad? - The MED-EL Blog<\/title>\n<meta name=\"description\" content=\"\u00bfCu\u00e1l es la relaci\u00f3n entre las resonancias magn\u00e9ticas y los IC? Lo que necesita es leer esta entrevista con Ellyce, ingeniera en resonancias de MED-EL, que comparte su experiencia desde Nueva Zelanda.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/blog.medel.com\/latam\/tecnologia-latam\/los-implantes-cocleares-y-la-seguridad-en-resonancias-magneticas\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Los implantes cocleares y la seguridad en resonancias magn\u00e9ticas (RMN): \u00bfQu\u00e9 significa esto en realidad? - The MED-EL Blog\" \/>\n<meta property=\"og:description\" content=\"\u00bfCu\u00e1l es la relaci\u00f3n entre las resonancias magn\u00e9ticas y los IC? Lo que necesita es leer esta entrevista con Ellyce, ingeniera en resonancias de MED-EL, que comparte su experiencia desde Nueva Zelanda.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/blog.medel.com\/latam\/tecnologia-latam\/los-implantes-cocleares-y-la-seguridad-en-resonancias-magneticas\/\" \/>\n<meta property=\"og:site_name\" content=\"The MED-EL Blog\" \/>\n<meta property=\"article:published_time\" content=\"2018-05-09T20:02:08+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-03-13T13:46:25+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/blog.medel.com\/wp-content\/uploads\/2023\/03\/ic_seguridad_resonancias.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1800\" \/>\n\t<meta property=\"og:image:height\" content=\"972\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"MED-EL\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"MED-EL\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/blog.medel.com\\\/latam\\\/tecnologia-latam\\\/los-implantes-cocleares-y-la-seguridad-en-resonancias-magneticas\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blog.medel.com\\\/latam\\\/tecnologia-latam\\\/los-implantes-cocleares-y-la-seguridad-en-resonancias-magneticas\\\/\"},\"author\":{\"name\":\"MED-EL\",\"@id\":\"https:\\\/\\\/blog.medel.com\\\/#\\\/schema\\\/person\\\/9f8dcfb27ec87796d874e021602c56e2\"},\"headline\":\"Los implantes cocleares y la seguridad en resonancias magn\u00e9ticas (RMN): \u00bfQu\u00e9 significa esto en realidad?\",\"datePublished\":\"2018-05-09T20:02:08+00:00\",\"dateModified\":\"2023-03-13T13:46:25+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/blog.medel.com\\\/latam\\\/tecnologia-latam\\\/los-implantes-cocleares-y-la-seguridad-en-resonancias-magneticas\\\/\"},\"wordCount\":750,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/blog.medel.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/blog.medel.com\\\/latam\\\/tecnologia-latam\\\/los-implantes-cocleares-y-la-seguridad-en-resonancias-magneticas\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/blog.medel.com\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/ic_seguridad_resonancias.jpg\",\"keywords\":[\"MED-EL\",\"MED-EL Latinoam\u00e9rica\",\"P\u00e9rdida Auditiva\",\"Soluciones Auditivas\"],\"articleSection\":[\"TECNOLOG\u00cdA\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/blog.medel.com\\\/latam\\\/tecnologia-latam\\\/los-implantes-cocleares-y-la-seguridad-en-resonancias-magneticas\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/blog.medel.com\\\/latam\\\/tecnologia-latam\\\/los-implantes-cocleares-y-la-seguridad-en-resonancias-magneticas\\\/\",\"url\":\"https:\\\/\\\/blog.medel.com\\\/latam\\\/tecnologia-latam\\\/los-implantes-cocleares-y-la-seguridad-en-resonancias-magneticas\\\/\",\"name\":\"Los implantes cocleares y la seguridad en resonancias magn\u00e9ticas (RMN): \u00bfQu\u00e9 significa esto en realidad? - The MED-EL Blog\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blog.medel.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/blog.medel.com\\\/latam\\\/tecnologia-latam\\\/los-implantes-cocleares-y-la-seguridad-en-resonancias-magneticas\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/blog.medel.com\\\/latam\\\/tecnologia-latam\\\/los-implantes-cocleares-y-la-seguridad-en-resonancias-magneticas\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/blog.medel.com\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/ic_seguridad_resonancias.jpg\",\"datePublished\":\"2018-05-09T20:02:08+00:00\",\"dateModified\":\"2023-03-13T13:46:25+00:00\",\"description\":\"\u00bfCu\u00e1l es la relaci\u00f3n entre las resonancias magn\u00e9ticas y los IC? Lo que necesita es leer esta entrevista con Ellyce, ingeniera en resonancias de MED-EL, que comparte su experiencia desde Nueva Zelanda.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/blog.medel.com\\\/latam\\\/tecnologia-latam\\\/los-implantes-cocleares-y-la-seguridad-en-resonancias-magneticas\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/blog.medel.com\\\/latam\\\/tecnologia-latam\\\/los-implantes-cocleares-y-la-seguridad-en-resonancias-magneticas\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/blog.medel.com\\\/latam\\\/tecnologia-latam\\\/los-implantes-cocleares-y-la-seguridad-en-resonancias-magneticas\\\/#primaryimage\",\"url\":\"https:\\\/\\\/blog.medel.com\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/ic_seguridad_resonancias.jpg\",\"contentUrl\":\"https:\\\/\\\/blog.medel.com\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/ic_seguridad_resonancias.jpg\",\"width\":1800,\"height\":972},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/blog.medel.com\\\/latam\\\/tecnologia-latam\\\/los-implantes-cocleares-y-la-seguridad-en-resonancias-magneticas\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/blog.medel.com\\\/latam\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Los implantes cocleares y la seguridad en resonancias magn\u00e9ticas (RMN): \u00bfQu\u00e9 significa esto en realidad?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/blog.medel.com\\\/#website\",\"url\":\"https:\\\/\\\/blog.medel.com\\\/\",\"name\":\"The MED-EL Blog\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/blog.medel.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/blog.medel.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/blog.medel.com\\\/#organization\",\"name\":\"The MED-EL Blog\",\"url\":\"https:\\\/\\\/blog.medel.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/blog.medel.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/blog.medel.com\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/MED-EL_logo_L2.png\",\"contentUrl\":\"https:\\\/\\\/blog.medel.com\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/MED-EL_logo_L2.png\",\"width\":443,\"height\":200,\"caption\":\"The MED-EL Blog\"},\"image\":{\"@id\":\"https:\\\/\\\/blog.medel.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/blog.medel.com\\\/#\\\/schema\\\/person\\\/9f8dcfb27ec87796d874e021602c56e2\",\"name\":\"MED-EL\",\"sameAs\":[\"https:\\\/\\\/www.medel.com\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Los implantes cocleares y la seguridad en resonancias magn\u00e9ticas (RMN): \u00bfQu\u00e9 significa esto en realidad? - The MED-EL Blog","description":"\u00bfCu\u00e1l es la relaci\u00f3n entre las resonancias magn\u00e9ticas y los IC? Lo que necesita es leer esta entrevista con Ellyce, ingeniera en resonancias de MED-EL, que comparte su experiencia desde Nueva Zelanda.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/blog.medel.com\/latam\/tecnologia-latam\/los-implantes-cocleares-y-la-seguridad-en-resonancias-magneticas\/","og_locale":"es_ES","og_type":"article","og_title":"Los implantes cocleares y la seguridad en resonancias magn\u00e9ticas (RMN): \u00bfQu\u00e9 significa esto en realidad? - The MED-EL Blog","og_description":"\u00bfCu\u00e1l es la relaci\u00f3n entre las resonancias magn\u00e9ticas y los IC? Lo que necesita es leer esta entrevista con Ellyce, ingeniera en resonancias de MED-EL, que comparte su experiencia desde Nueva Zelanda.","og_url":"https:\/\/blog.medel.com\/latam\/tecnologia-latam\/los-implantes-cocleares-y-la-seguridad-en-resonancias-magneticas\/","og_site_name":"The MED-EL Blog","article_published_time":"2018-05-09T20:02:08+00:00","article_modified_time":"2023-03-13T13:46:25+00:00","og_image":[{"width":1800,"height":972,"url":"https:\/\/blog.medel.com\/wp-content\/uploads\/2023\/03\/ic_seguridad_resonancias.jpg","type":"image\/jpeg"}],"author":"MED-EL","twitter_card":"summary_large_image","twitter_misc":{"Written by":"MED-EL","Est. reading time":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/blog.medel.com\/latam\/tecnologia-latam\/los-implantes-cocleares-y-la-seguridad-en-resonancias-magneticas\/#article","isPartOf":{"@id":"https:\/\/blog.medel.com\/latam\/tecnologia-latam\/los-implantes-cocleares-y-la-seguridad-en-resonancias-magneticas\/"},"author":{"name":"MED-EL","@id":"https:\/\/blog.medel.com\/#\/schema\/person\/9f8dcfb27ec87796d874e021602c56e2"},"headline":"Los implantes cocleares y la seguridad en resonancias magn\u00e9ticas (RMN): \u00bfQu\u00e9 significa esto en realidad?","datePublished":"2018-05-09T20:02:08+00:00","dateModified":"2023-03-13T13:46:25+00:00","mainEntityOfPage":{"@id":"https:\/\/blog.medel.com\/latam\/tecnologia-latam\/los-implantes-cocleares-y-la-seguridad-en-resonancias-magneticas\/"},"wordCount":750,"commentCount":0,"publisher":{"@id":"https:\/\/blog.medel.com\/#organization"},"image":{"@id":"https:\/\/blog.medel.com\/latam\/tecnologia-latam\/los-implantes-cocleares-y-la-seguridad-en-resonancias-magneticas\/#primaryimage"},"thumbnailUrl":"https:\/\/blog.medel.com\/wp-content\/uploads\/2023\/03\/ic_seguridad_resonancias.jpg","keywords":["MED-EL","MED-EL Latinoam\u00e9rica","P\u00e9rdida Auditiva","Soluciones Auditivas"],"articleSection":["TECNOLOG\u00cdA"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/blog.medel.com\/latam\/tecnologia-latam\/los-implantes-cocleares-y-la-seguridad-en-resonancias-magneticas\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/blog.medel.com\/latam\/tecnologia-latam\/los-implantes-cocleares-y-la-seguridad-en-resonancias-magneticas\/","url":"https:\/\/blog.medel.com\/latam\/tecnologia-latam\/los-implantes-cocleares-y-la-seguridad-en-resonancias-magneticas\/","name":"Los implantes cocleares y la seguridad en resonancias magn\u00e9ticas (RMN): \u00bfQu\u00e9 significa esto en realidad? - The MED-EL Blog","isPartOf":{"@id":"https:\/\/blog.medel.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/blog.medel.com\/latam\/tecnologia-latam\/los-implantes-cocleares-y-la-seguridad-en-resonancias-magneticas\/#primaryimage"},"image":{"@id":"https:\/\/blog.medel.com\/latam\/tecnologia-latam\/los-implantes-cocleares-y-la-seguridad-en-resonancias-magneticas\/#primaryimage"},"thumbnailUrl":"https:\/\/blog.medel.com\/wp-content\/uploads\/2023\/03\/ic_seguridad_resonancias.jpg","datePublished":"2018-05-09T20:02:08+00:00","dateModified":"2023-03-13T13:46:25+00:00","description":"\u00bfCu\u00e1l es la relaci\u00f3n entre las resonancias magn\u00e9ticas y los IC? Lo que necesita es leer esta entrevista con Ellyce, ingeniera en resonancias de MED-EL, que comparte su experiencia desde Nueva Zelanda.","breadcrumb":{"@id":"https:\/\/blog.medel.com\/latam\/tecnologia-latam\/los-implantes-cocleares-y-la-seguridad-en-resonancias-magneticas\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/blog.medel.com\/latam\/tecnologia-latam\/los-implantes-cocleares-y-la-seguridad-en-resonancias-magneticas\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/blog.medel.com\/latam\/tecnologia-latam\/los-implantes-cocleares-y-la-seguridad-en-resonancias-magneticas\/#primaryimage","url":"https:\/\/blog.medel.com\/wp-content\/uploads\/2023\/03\/ic_seguridad_resonancias.jpg","contentUrl":"https:\/\/blog.medel.com\/wp-content\/uploads\/2023\/03\/ic_seguridad_resonancias.jpg","width":1800,"height":972},{"@type":"BreadcrumbList","@id":"https:\/\/blog.medel.com\/latam\/tecnologia-latam\/los-implantes-cocleares-y-la-seguridad-en-resonancias-magneticas\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/blog.medel.com\/latam\/"},{"@type":"ListItem","position":2,"name":"Los implantes cocleares y la seguridad en resonancias magn\u00e9ticas (RMN): \u00bfQu\u00e9 significa esto en realidad?"}]},{"@type":"WebSite","@id":"https:\/\/blog.medel.com\/#website","url":"https:\/\/blog.medel.com\/","name":"The MED-EL Blog","description":"","publisher":{"@id":"https:\/\/blog.medel.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/blog.medel.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/blog.medel.com\/#organization","name":"The MED-EL Blog","url":"https:\/\/blog.medel.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/blog.medel.com\/#\/schema\/logo\/image\/","url":"https:\/\/blog.medel.com\/wp-content\/uploads\/2023\/02\/MED-EL_logo_L2.png","contentUrl":"https:\/\/blog.medel.com\/wp-content\/uploads\/2023\/02\/MED-EL_logo_L2.png","width":443,"height":200,"caption":"The MED-EL Blog"},"image":{"@id":"https:\/\/blog.medel.com\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/blog.medel.com\/#\/schema\/person\/9f8dcfb27ec87796d874e021602c56e2","name":"MED-EL","sameAs":["https:\/\/www.medel.com"]}]}},"_links":{"self":[{"href":"https:\/\/blog.medel.com\/latam\/wp-json\/wp\/v2\/posts\/53381","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.medel.com\/latam\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.medel.com\/latam\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.medel.com\/latam\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.medel.com\/latam\/wp-json\/wp\/v2\/comments?post=53381"}],"version-history":[{"count":1,"href":"https:\/\/blog.medel.com\/latam\/wp-json\/wp\/v2\/posts\/53381\/revisions"}],"predecessor-version":[{"id":53382,"href":"https:\/\/blog.medel.com\/latam\/wp-json\/wp\/v2\/posts\/53381\/revisions\/53382"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blog.medel.com\/latam\/wp-json\/wp\/v2\/media\/69751"}],"wp:attachment":[{"href":"https:\/\/blog.medel.com\/latam\/wp-json\/wp\/v2\/media?parent=53381"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.medel.com\/latam\/wp-json\/wp\/v2\/categories?post=53381"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.medel.com\/latam\/wp-json\/wp\/v2\/tags?post=53381"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}