{"id":3080,"count":1,"description":"","link":"https:\/\/blog.medel.com\/id\/tag\/adhd\/","name":"adhd","slug":"adhd","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>adhd Archives - The MED-EL Blog<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/blog.medel.com\/id\/tag\/adhd\/\" \/>\n<meta property=\"og:locale\" content=\"id_ID\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"adhd Archives - The MED-EL Blog\" \/>\n<meta property=\"og:url\" content=\"https:\/\/blog.medel.com\/id\/tag\/adhd\/\" \/>\n<meta property=\"og:site_name\" content=\"The MED-EL Blog\" \/>\n<meta property=\"og:image\" content=\"https:\/\/blog.medel.com\/wp-content\/uploads\/2023\/02\/MED-EL_logo_L2.png\" \/>\n\t<meta property=\"og:image:width\" content=\"443\" \/>\n\t<meta property=\"og:image:height\" content=\"200\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/blog.medel.com\\\/id\\\/tag\\\/adhd\\\/\",\"url\":\"https:\\\/\\\/blog.medel.com\\\/id\\\/tag\\\/adhd\\\/\",\"name\":\"adhd Archives - The MED-EL Blog\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blog.medel.com\\\/ka\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/blog.medel.com\\\/id\\\/tag\\\/adhd\\\/#breadcrumb\"},\"inLanguage\":\"id-ID\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/blog.medel.com\\\/id\\\/tag\\\/adhd\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/blog.medel.com\\\/id\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"adhd\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/blog.medel.com\\\/ka\\\/#website\",\"url\":\"https:\\\/\\\/blog.medel.com\\\/ka\\\/\",\"name\":\"The MED-EL Blog\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/blog.medel.com\\\/ka\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/blog.medel.com\\\/ka\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"id-ID\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/blog.medel.com\\\/ka\\\/#organization\",\"name\":\"The MED-EL Blog\",\"url\":\"https:\\\/\\\/blog.medel.com\\\/ka\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"id-ID\",\"@id\":\"https:\\\/\\\/blog.medel.com\\\/ka\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/blog.medel.com\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/MED-EL_logo_L2.png\",\"contentUrl\":\"https:\\\/\\\/blog.medel.com\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/MED-EL_logo_L2.png\",\"width\":443,\"height\":200,\"caption\":\"The MED-EL Blog\"},\"image\":{\"@id\":\"https:\\\/\\\/blog.medel.com\\\/ka\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"adhd Archives - The MED-EL Blog","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/blog.medel.com\/id\/tag\/adhd\/","og_locale":"id_ID","og_type":"article","og_title":"adhd Archives - The MED-EL Blog","og_url":"https:\/\/blog.medel.com\/id\/tag\/adhd\/","og_site_name":"The MED-EL Blog","og_image":[{"width":443,"height":200,"url":"https:\/\/blog.medel.com\/wp-content\/uploads\/2023\/02\/MED-EL_logo_L2.png","type":"image\/png"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/blog.medel.com\/id\/tag\/adhd\/","url":"https:\/\/blog.medel.com\/id\/tag\/adhd\/","name":"adhd Archives - The MED-EL Blog","isPartOf":{"@id":"https:\/\/blog.medel.com\/ka\/#website"},"breadcrumb":{"@id":"https:\/\/blog.medel.com\/id\/tag\/adhd\/#breadcrumb"},"inLanguage":"id-ID"},{"@type":"BreadcrumbList","@id":"https:\/\/blog.medel.com\/id\/tag\/adhd\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/blog.medel.com\/id\/"},{"@type":"ListItem","position":2,"name":"adhd"}]},{"@type":"WebSite","@id":"https:\/\/blog.medel.com\/ka\/#website","url":"https:\/\/blog.medel.com\/ka\/","name":"The MED-EL Blog","description":"","publisher":{"@id":"https:\/\/blog.medel.com\/ka\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/blog.medel.com\/ka\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"id-ID"},{"@type":"Organization","@id":"https:\/\/blog.medel.com\/ka\/#organization","name":"The MED-EL Blog","url":"https:\/\/blog.medel.com\/ka\/","logo":{"@type":"ImageObject","inLanguage":"id-ID","@id":"https:\/\/blog.medel.com\/ka\/#\/schema\/logo\/image\/","url":"https:\/\/blog.medel.com\/wp-content\/uploads\/2023\/02\/MED-EL_logo_L2.png","contentUrl":"https:\/\/blog.medel.com\/wp-content\/uploads\/2023\/02\/MED-EL_logo_L2.png","width":443,"height":200,"caption":"The MED-EL Blog"},"image":{"@id":"https:\/\/blog.medel.com\/ka\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/blog.medel.com\/id\/wp-json\/wp\/v2\/tags\/3080","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.medel.com\/id\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/blog.medel.com\/id\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/blog.medel.com\/id\/wp-json\/wp\/v2\/posts?tags=3080"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}