{"id":46849,"date":"2019-06-07T04:30:42","date_gmt":"2019-06-07T04:30:42","guid":{"rendered":"https:\/\/blog.medel.com\/unkategorisiert\/esteban-lopez-ein-inspirierender-tierarzt-mit-cochlea-implantaten\/"},"modified":"2023-04-05T09:01:27","modified_gmt":"2023-04-05T09:01:27","slug":"esteban-lopez-ein-inspirierender-tierarzt-mit-cochlea-implantaten","status":"publish","type":"post","link":"https:\/\/blog.medel.com\/de\/gastartikel\/esteban-lopez-ein-inspirierender-tierarzt-mit-cochlea-implantaten\/","title":{"rendered":"Esteban L\u00f3pez, ein inspirierender Tierarzt mit Cochlea-Implantaten"},"content":{"rendered":"<p>H\u00f6rverlust war von Geburt an ein Teil von Esteban L\u00f3pez\u2018 Leben. Mithilfe von H\u00f6rger\u00e4ten meisterte er erfolgreich die Schule und erf\u00fcllte sich mit dem Studium der Tiermedizin einen Traum. Doch selbst mit den st\u00e4rksten H\u00f6rger\u00e4ten hatte er bei der Arbeit Probleme, Menschen (und Tiere!) klar und deutlich zu verstehen. Da fasste Esteban den Entschluss, sich mit Cochlea-Implantaten versorgen zu lassen.<\/p>\n<p>Heute ist seine Arbeit als Tierarzt unkomplizierter als je zuvor. Er lernt eine neue Sprache und er hat sogar ein spezielles voreingestelltes H\u00f6rprogramm f\u00fcr sein Stethoskop! Uns hat Esteban von seinem Weg zu den Cochlea-Implantaten erz\u00e4hlt und verraten, was er sich f\u00fcr die Zukunft w\u00fcnscht.<\/p>\n<hr \/>\n<p>&nbsp;<\/p>\n<p>Mein Name ist Esteban L\u00f3pez und ich bin 45 Jahre alt. Ich komme aus Argentinien und arbeite seit 2009 als Tierarzt. Seit meiner Kindheit habe ich eine gro\u00dfe Leidenschaft f\u00fcr Tiere und wusste schon fr\u00fch, dass ich Tierarzt werden wollte. Der Weg dorthin war aber ein wirklich langer, beschwerlicher und manchmal schmerzhafter. Ich wurde taub geboren, meine Schulzeit und die Ausbildung an der Universit\u00e4t waren nicht einfach f\u00fcr mich. Dennoch habe ich mein Karriereziel erreicht.<\/p>\n<p>&nbsp;<\/p>\n<h3><strong>Kindheit mit H\u00f6rverlust <\/strong><\/h3>\n<p>H\u00f6rverlust hat mich in vielerlei Hinsicht beeinflusst. In meiner Kindheit und Jugend wurde ich von meinen Mitsch\u00fclern schikaniert und musste die Gleichg\u00fcltigkeit vieler Lehrer und die Unt\u00e4tigkeit von Schuldirektoren erleben. Aber ich bin meinen Weg gegangen und konnte die Grund- und Sekundarschule erfolgreich abschlie\u00dfen.<\/p>\n<p>Mit einer wirklich gro\u00dfen Herausforderung war ich konfrontiert, als ich an der Universit\u00e4t Tiermedizin studierte und ein Stethoskop verwenden musste. Es war mir unm\u00f6glich, die Herz- oder Lungenger\u00e4usche zu h\u00f6ren. Zuf\u00e4llig fand ich ein altes elektronisches Stethoskop aus Japan, das recht gut funktionierte. Ich konnte es \u00fcber Bluetooth mit meinen H\u00f6rger\u00e4ten verbinden.<\/p>\n<p>&nbsp;<\/p>\n<h3><strong>Von H\u00f6rger\u00e4ten zu Cochlea-Implantaten<\/strong><\/h3>\n<p>Seit meiner Diagnose im Alter von drei Jahren habe ich H\u00f6rger\u00e4te benutzt. Weil mein rechtes Ohr als \u201enicht funktionst\u00fcchtig\u201c eingestuft wurde, verwendete ich nur links ein H\u00f6rger\u00e4t. Erst mit 34 Jahren bekam ich auch auf dem rechten Ohr ein leistungsstarkes H\u00f6rger\u00e4t. Dadurch besserte sich meine H\u00f6rleistung zwar geringf\u00fcgig, Ger\u00e4usche unterscheiden konnte ich aber weiterhin nicht. Um Sprache besser verstehen zu k\u00f6nnen, war ich st\u00e4ndig auf der Suche nach den st\u00e4rksten H\u00f6rger\u00e4ten auf dem Markt.<\/p>\n<p>Lange Zeit war ich mir in Sachen Cochlea-Implantat unsicher. Nach dem Event eines Cochlea-Implantat-Herstellers begann ich erstmals konkret \u00fcber ein CI nachzudenken. Ich traf viele Menschen mit Implantat und war \u00fcberrascht, wie gut sie h\u00f6ren konnten und wie sehr ein CI ihr Leben ver\u00e4ndert hatte.<\/p>\n<p>Zur\u00fcck in der Stadt ging ich zu meiner Audiologin Gabriela Dotto, die mir schon lange ein Implantat empfohlen hatte. Nun folgte ich ihrer Empfehlung. Sie empfahl mir MED-EL &#8211; ein f\u00fcr mich damals noch v\u00f6llig unbekanntes Unternehmen. Noch am selben Abend fuhr ich den Computer hoch und fand alles, was ich wissen wollte. Ich war fasziniert von der Geschichte und den technologischen Errungenschaften von MED-EL. In diesem Moment entschied ich mich f\u00fcr ein MED-EL Implantat und bin heute sehr froh \u00fcber meine Entscheidung.<\/p>\n<p>&nbsp;<\/p>\n<h3><strong>Mein Weg zu Cochlea-Implantaten: Operation und Aktivierung <\/strong><\/h3>\n<p>Im Januar 2018 f\u00fchrte Dr. Lucas Comelli die erste Operation an meinem rechten Ohr im Privatkrankenhaus in Rosario, Argentinien, durch. Aufgrund der ungew\u00f6hnlichen Lage meiner Cochlea und der geringen Gr\u00f6\u00dfe des ovalen Fensters verlief die Operation langsamer als gew\u00f6hnlich und dauerte l\u00e4nger. Nach der Operation erholte ich mich aber rasch w\u00e4hrend der f\u00fcnf Tage, die ich zuhause verbringen musste. 21 Tage nach der Operation wurde mein Implantat schlie\u00dflich aktiviert.<\/p>\n<p>Die Aktivierung war seltsam\u2026 Ich f\u00fchlte zwar, dass das Implantat nun aktiv war. Aber ich hatte eigentlich erwartet, sofort h\u00f6ren zu k\u00f6nnen &#8211; und so war es nicht.<\/p>\n<p>Die zweite Operation hatte ich dann im September letzten Jahres. Die Aktivierung war ganz anders als die erste: Zuerst begann ich, Ger\u00e4usche und Stimmen wahrzunehmen und zu f\u00fchlen. Die ersten paar Tage h\u00f6rte sich alles gleich an. Aber dann wurden die Dinge deutlicher und ich konnte die Stimmen verschiedener Personen unterscheiden.<\/p>\n<p>Die gr\u00f6\u00dfte Ver\u00e4nderung f\u00fcr mich war, als ich mit meinem rechten Ohr Ger\u00e4usche zu h\u00f6ren begann &#8211; nachdem ich es quasi 44 Jahre lang nicht genutzt hatte. Heute kann ich den Klang des Buchstabens &#8222;s&#8220; besser als je zuvor erkennen. Die Unterscheidung von W\u00f6rtern funktioniert fast perfekt &#8211; ohne \u201eVerz\u00f6gerung\u201c &#8211; und ich kann sogar am Telefon sprechen. Mein erstes Telefongespr\u00e4ch f\u00fchrte ich nur 21 Tage nach der Aktivierung meines linken Implantats.<\/p>\n<p>&nbsp;<\/p>\n<h3><strong>Ein einfacherer Arbeitsalltag <\/strong><\/h3>\n<p>Bei der Arbeit helfen mir meine Implantate enorm, besonders in lauten Umgebungen. Sie helfen mir dabei, W\u00f6rter besser zu unterscheiden und sogar besser zu sprechen: Ich rede jetzt nicht mehr so laut oder n\u00e4selnd wie vorher, sondern tiefer und deutlicher. Dass meine Arbeitskollegen und die Besitzer meiner tierischen Patienten \u00fcber meine Implantate Bescheid wissen, macht die t\u00e4gliche Arbeit nat\u00fcrlich auch einfacher.<\/p>\n<p>Ich habe sogar eine speziell angepasstes H\u00f6rprogramm f\u00fcr mein Stethoskop: Meine Audiologin Gabriella Dotto hat eine Einstellung speziell f\u00fcr die Anwendung mit dem elektronischen Stethoskop kreiert. Im Grunde werden dabei die Elektroden f\u00fcr die Tiefen und H\u00f6hen angepasst. Denn bei Herzt\u00f6nen handelt es sich vorwiegend um Basskl\u00e4nge (Murmeln) mit einem sehr fl\u00fcchtigen Anteil an H\u00f6hen (z.B. bei Ventilschlie\u00dfungen).<\/p>\n<p>Ich verbinde das Stethoskop \u00fcber das rote Audiokabel mit dem SONNET (90 % Audio und 10 % Mikrofon). Da aber auch Umgebungsger\u00e4usche vom Stethoskop aufgenommen werden, ist eine sehr ruhige Umgebung wichtig.<\/p>\n<p>Nat\u00fcrlich gibt es nach wie vor Herausforderungen. Ich lerne Deutsch und habe gerade meinen dritten Kurs begonnen. Nach der Aktivierung meines ersten Implantats gab es eine Phase, so ungef\u00e4hr einen Monat lang, in der ich Probleme hatte, die deutschen Umlaute <em>\u00e4<\/em>, <em>\u00f6<\/em> und <em>\u00fc<\/em> zu unterscheiden. Aber zum Gl\u00fcck halfen mir die anderen Kursteilnehmer und der Lehrer, alles zu verstehen, und schrieben Worte, die ich nicht verstehen konnte, einfach auf die Tafel.<\/p>\n<p>Jetzt, mit zwei Implantaten, hoffe ich meinen Deutschkurs abschlie\u00dfen zu k\u00f6nnen und meine eigenen Grenzen zu \u00fcberschreiten!<\/p>\n<p><em>Danke, Esteban!\u00a0 <\/em><\/p>\n<p><em>\u00a0<\/em><\/p>\n<p><em>Erfahren Sie <a href=\"\/?p=4888\" target=\"_blank\" rel=\"noopener noreferrer\">10 Faktoren, die bei Erwachsenen das H\u00f6ren mit einem Cochleaimplantat beeinflussen<\/a><\/em><em>. <\/em><\/p>\n<p><em>Sie m\u00f6chten keinen der neuesten Gastbeitr\u00e4ge, Tipps und Tricks oder Informationen zu MED-EL H\u00f6rl\u00f6sungen verpassen? Dann <a href=\"\/?page_id=4960\" target=\"_blank\" rel=\"noopener noreferrer\">abonnieren Sie den MED-EL Blog<\/a><\/em><em>\u00a0und erhalten Sie die neuesten Blog-Artikel direkt in Ihren Posteingang! <\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>H\u00f6rverlust war von Geburt an ein Teil von Esteban L\u00f3pez\u2018 Leben. Mithilfe von H\u00f6rger\u00e4ten meisterte er erfolgreich die Schule und erf\u00fcllte sich mit dem Studium der Tiermedizin einen Traum. Doch selbst mit den st\u00e4rksten H\u00f6rger\u00e4ten hatte er bei der Arbeit Probleme, Menschen (und Tiere!) klar und deutlich zu verstehen. Da fasste Esteban den Entschluss, sich [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":64861,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2881],"tags":[2721,2732,2729,2737],"class_list":["post-46849","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-gastartikel","tag-cochlea-implantat","tag-horen","tag-horgerat","tag-innenohrschwerhorigkeit"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Esteban L\u00f3pez, ein inspirierender Tierarzt mit Cochlea-Implantaten - The MED-EL Blog<\/title>\n<meta name=\"description\" content=\"Esteban L\u00f3pez aus Argentinien hat von Geburt an H\u00f6rverlust. Heute ist er bilateraler CI-Nutzer und Tierarzt aus Leidenschaft.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/blog.medel.com\/de\/gastartikel\/esteban-lopez-ein-inspirierender-tierarzt-mit-cochlea-implantaten\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Esteban L\u00f3pez, ein inspirierender Tierarzt mit Cochlea-Implantaten - The MED-EL Blog\" \/>\n<meta property=\"og:description\" content=\"Esteban L\u00f3pez aus Argentinien hat von Geburt an H\u00f6rverlust. Heute ist er bilateraler CI-Nutzer und Tierarzt aus Leidenschaft.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/blog.medel.com\/de\/gastartikel\/esteban-lopez-ein-inspirierender-tierarzt-mit-cochlea-implantaten\/\" \/>\n<meta property=\"og:site_name\" content=\"The MED-EL Blog\" \/>\n<meta property=\"article:published_time\" content=\"2019-06-07T04:30:42+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-04-05T09:01:27+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/blog.medel.com\/wp-content\/uploads\/2023\/03\/vet-with-cochlear-implants-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2422\" \/>\n\t<meta property=\"og:image:height\" content=\"1211\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"MED-EL\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"MED-EL\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/blog.medel.com\\\/de\\\/gastartikel\\\/esteban-lopez-ein-inspirierender-tierarzt-mit-cochlea-implantaten\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blog.medel.com\\\/de\\\/gastartikel\\\/esteban-lopez-ein-inspirierender-tierarzt-mit-cochlea-implantaten\\\/\"},\"author\":{\"name\":\"MED-EL\",\"@id\":\"https:\\\/\\\/blog.medel.com\\\/de\\\/#\\\/schema\\\/person\\\/9f8dcfb27ec87796d874e021602c56e2\"},\"headline\":\"Esteban L\u00f3pez, ein inspirierender Tierarzt mit Cochlea-Implantaten\",\"datePublished\":\"2019-06-07T04:30:42+00:00\",\"dateModified\":\"2023-04-05T09:01:27+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/blog.medel.com\\\/de\\\/gastartikel\\\/esteban-lopez-ein-inspirierender-tierarzt-mit-cochlea-implantaten\\\/\"},\"wordCount\":1104,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/blog.medel.com\\\/de\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/blog.medel.com\\\/de\\\/gastartikel\\\/esteban-lopez-ein-inspirierender-tierarzt-mit-cochlea-implantaten\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/blog.medel.com\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/vet-with-cochlear-implants-1.jpg\",\"keywords\":[\"Cochlea-Implantat\",\"H\u00f6ren\",\"H\u00f6rger\u00e4t\",\"Innenohrschwerh\u00f6rigkeit\"],\"articleSection\":[\"Gastartikel\"],\"inLanguage\":\"de-DE\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/blog.medel.com\\\/de\\\/gastartikel\\\/esteban-lopez-ein-inspirierender-tierarzt-mit-cochlea-implantaten\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/blog.medel.com\\\/de\\\/gastartikel\\\/esteban-lopez-ein-inspirierender-tierarzt-mit-cochlea-implantaten\\\/\",\"url\":\"https:\\\/\\\/blog.medel.com\\\/de\\\/gastartikel\\\/esteban-lopez-ein-inspirierender-tierarzt-mit-cochlea-implantaten\\\/\",\"name\":\"Esteban L\u00f3pez, ein inspirierender Tierarzt mit Cochlea-Implantaten - The MED-EL Blog\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blog.medel.com\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/blog.medel.com\\\/de\\\/gastartikel\\\/esteban-lopez-ein-inspirierender-tierarzt-mit-cochlea-implantaten\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/blog.medel.com\\\/de\\\/gastartikel\\\/esteban-lopez-ein-inspirierender-tierarzt-mit-cochlea-implantaten\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/blog.medel.com\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/vet-with-cochlear-implants-1.jpg\",\"datePublished\":\"2019-06-07T04:30:42+00:00\",\"dateModified\":\"2023-04-05T09:01:27+00:00\",\"description\":\"Esteban L\u00f3pez aus Argentinien hat von Geburt an H\u00f6rverlust. Heute ist er bilateraler CI-Nutzer und Tierarzt aus Leidenschaft.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/blog.medel.com\\\/de\\\/gastartikel\\\/esteban-lopez-ein-inspirierender-tierarzt-mit-cochlea-implantaten\\\/#breadcrumb\"},\"inLanguage\":\"de-DE\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/blog.medel.com\\\/de\\\/gastartikel\\\/esteban-lopez-ein-inspirierender-tierarzt-mit-cochlea-implantaten\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de-DE\",\"@id\":\"https:\\\/\\\/blog.medel.com\\\/de\\\/gastartikel\\\/esteban-lopez-ein-inspirierender-tierarzt-mit-cochlea-implantaten\\\/#primaryimage\",\"url\":\"https:\\\/\\\/blog.medel.com\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/vet-with-cochlear-implants-1.jpg\",\"contentUrl\":\"https:\\\/\\\/blog.medel.com\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/vet-with-cochlear-implants-1.jpg\",\"width\":2422,\"height\":1211},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/blog.medel.com\\\/de\\\/gastartikel\\\/esteban-lopez-ein-inspirierender-tierarzt-mit-cochlea-implantaten\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/blog.medel.com\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Esteban L\u00f3pez, ein inspirierender Tierarzt mit Cochlea-Implantaten\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/blog.medel.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/blog.medel.com\\\/de\\\/\",\"name\":\"The MED-EL Blog\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/blog.medel.com\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/blog.medel.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de-DE\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/blog.medel.com\\\/de\\\/#organization\",\"name\":\"The MED-EL Blog\",\"url\":\"https:\\\/\\\/blog.medel.com\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de-DE\",\"@id\":\"https:\\\/\\\/blog.medel.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/blog.medel.com\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/MED-EL_logo_L2.png\",\"contentUrl\":\"https:\\\/\\\/blog.medel.com\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/MED-EL_logo_L2.png\",\"width\":443,\"height\":200,\"caption\":\"The MED-EL Blog\"},\"image\":{\"@id\":\"https:\\\/\\\/blog.medel.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/blog.medel.com\\\/de\\\/#\\\/schema\\\/person\\\/9f8dcfb27ec87796d874e021602c56e2\",\"name\":\"MED-EL\",\"sameAs\":[\"https:\\\/\\\/www.medel.com\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Esteban L\u00f3pez, ein inspirierender Tierarzt mit Cochlea-Implantaten - The MED-EL Blog","description":"Esteban L\u00f3pez aus Argentinien hat von Geburt an H\u00f6rverlust. Heute ist er bilateraler CI-Nutzer und Tierarzt aus Leidenschaft.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/blog.medel.com\/de\/gastartikel\/esteban-lopez-ein-inspirierender-tierarzt-mit-cochlea-implantaten\/","og_locale":"de_DE","og_type":"article","og_title":"Esteban L\u00f3pez, ein inspirierender Tierarzt mit Cochlea-Implantaten - The MED-EL Blog","og_description":"Esteban L\u00f3pez aus Argentinien hat von Geburt an H\u00f6rverlust. Heute ist er bilateraler CI-Nutzer und Tierarzt aus Leidenschaft.","og_url":"https:\/\/blog.medel.com\/de\/gastartikel\/esteban-lopez-ein-inspirierender-tierarzt-mit-cochlea-implantaten\/","og_site_name":"The MED-EL Blog","article_published_time":"2019-06-07T04:30:42+00:00","article_modified_time":"2023-04-05T09:01:27+00:00","og_image":[{"width":2422,"height":1211,"url":"https:\/\/blog.medel.com\/wp-content\/uploads\/2023\/03\/vet-with-cochlear-implants-1.jpg","type":"image\/jpeg"}],"author":"MED-EL","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"MED-EL","Gesch\u00e4tzte Lesezeit":"5 Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/blog.medel.com\/de\/gastartikel\/esteban-lopez-ein-inspirierender-tierarzt-mit-cochlea-implantaten\/#article","isPartOf":{"@id":"https:\/\/blog.medel.com\/de\/gastartikel\/esteban-lopez-ein-inspirierender-tierarzt-mit-cochlea-implantaten\/"},"author":{"name":"MED-EL","@id":"https:\/\/blog.medel.com\/de\/#\/schema\/person\/9f8dcfb27ec87796d874e021602c56e2"},"headline":"Esteban L\u00f3pez, ein inspirierender Tierarzt mit Cochlea-Implantaten","datePublished":"2019-06-07T04:30:42+00:00","dateModified":"2023-04-05T09:01:27+00:00","mainEntityOfPage":{"@id":"https:\/\/blog.medel.com\/de\/gastartikel\/esteban-lopez-ein-inspirierender-tierarzt-mit-cochlea-implantaten\/"},"wordCount":1104,"commentCount":0,"publisher":{"@id":"https:\/\/blog.medel.com\/de\/#organization"},"image":{"@id":"https:\/\/blog.medel.com\/de\/gastartikel\/esteban-lopez-ein-inspirierender-tierarzt-mit-cochlea-implantaten\/#primaryimage"},"thumbnailUrl":"https:\/\/blog.medel.com\/wp-content\/uploads\/2023\/03\/vet-with-cochlear-implants-1.jpg","keywords":["Cochlea-Implantat","H\u00f6ren","H\u00f6rger\u00e4t","Innenohrschwerh\u00f6rigkeit"],"articleSection":["Gastartikel"],"inLanguage":"de-DE","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/blog.medel.com\/de\/gastartikel\/esteban-lopez-ein-inspirierender-tierarzt-mit-cochlea-implantaten\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/blog.medel.com\/de\/gastartikel\/esteban-lopez-ein-inspirierender-tierarzt-mit-cochlea-implantaten\/","url":"https:\/\/blog.medel.com\/de\/gastartikel\/esteban-lopez-ein-inspirierender-tierarzt-mit-cochlea-implantaten\/","name":"Esteban L\u00f3pez, ein inspirierender Tierarzt mit Cochlea-Implantaten - The MED-EL Blog","isPartOf":{"@id":"https:\/\/blog.medel.com\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/blog.medel.com\/de\/gastartikel\/esteban-lopez-ein-inspirierender-tierarzt-mit-cochlea-implantaten\/#primaryimage"},"image":{"@id":"https:\/\/blog.medel.com\/de\/gastartikel\/esteban-lopez-ein-inspirierender-tierarzt-mit-cochlea-implantaten\/#primaryimage"},"thumbnailUrl":"https:\/\/blog.medel.com\/wp-content\/uploads\/2023\/03\/vet-with-cochlear-implants-1.jpg","datePublished":"2019-06-07T04:30:42+00:00","dateModified":"2023-04-05T09:01:27+00:00","description":"Esteban L\u00f3pez aus Argentinien hat von Geburt an H\u00f6rverlust. Heute ist er bilateraler CI-Nutzer und Tierarzt aus Leidenschaft.","breadcrumb":{"@id":"https:\/\/blog.medel.com\/de\/gastartikel\/esteban-lopez-ein-inspirierender-tierarzt-mit-cochlea-implantaten\/#breadcrumb"},"inLanguage":"de-DE","potentialAction":[{"@type":"ReadAction","target":["https:\/\/blog.medel.com\/de\/gastartikel\/esteban-lopez-ein-inspirierender-tierarzt-mit-cochlea-implantaten\/"]}]},{"@type":"ImageObject","inLanguage":"de-DE","@id":"https:\/\/blog.medel.com\/de\/gastartikel\/esteban-lopez-ein-inspirierender-tierarzt-mit-cochlea-implantaten\/#primaryimage","url":"https:\/\/blog.medel.com\/wp-content\/uploads\/2023\/03\/vet-with-cochlear-implants-1.jpg","contentUrl":"https:\/\/blog.medel.com\/wp-content\/uploads\/2023\/03\/vet-with-cochlear-implants-1.jpg","width":2422,"height":1211},{"@type":"BreadcrumbList","@id":"https:\/\/blog.medel.com\/de\/gastartikel\/esteban-lopez-ein-inspirierender-tierarzt-mit-cochlea-implantaten\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/blog.medel.com\/de\/"},{"@type":"ListItem","position":2,"name":"Esteban L\u00f3pez, ein inspirierender Tierarzt mit Cochlea-Implantaten"}]},{"@type":"WebSite","@id":"https:\/\/blog.medel.com\/de\/#website","url":"https:\/\/blog.medel.com\/de\/","name":"The MED-EL Blog","description":"","publisher":{"@id":"https:\/\/blog.medel.com\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/blog.medel.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de-DE"},{"@type":"Organization","@id":"https:\/\/blog.medel.com\/de\/#organization","name":"The MED-EL Blog","url":"https:\/\/blog.medel.com\/de\/","logo":{"@type":"ImageObject","inLanguage":"de-DE","@id":"https:\/\/blog.medel.com\/de\/#\/schema\/logo\/image\/","url":"https:\/\/blog.medel.com\/wp-content\/uploads\/2023\/02\/MED-EL_logo_L2.png","contentUrl":"https:\/\/blog.medel.com\/wp-content\/uploads\/2023\/02\/MED-EL_logo_L2.png","width":443,"height":200,"caption":"The MED-EL Blog"},"image":{"@id":"https:\/\/blog.medel.com\/de\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/blog.medel.com\/de\/#\/schema\/person\/9f8dcfb27ec87796d874e021602c56e2","name":"MED-EL","sameAs":["https:\/\/www.medel.com"]}]}},"_links":{"self":[{"href":"https:\/\/blog.medel.com\/de\/wp-json\/wp\/v2\/posts\/46849","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.medel.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.medel.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.medel.com\/de\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.medel.com\/de\/wp-json\/wp\/v2\/comments?post=46849"}],"version-history":[{"count":1,"href":"https:\/\/blog.medel.com\/de\/wp-json\/wp\/v2\/posts\/46849\/revisions"}],"predecessor-version":[{"id":47105,"href":"https:\/\/blog.medel.com\/de\/wp-json\/wp\/v2\/posts\/46849\/revisions\/47105"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blog.medel.com\/de\/wp-json\/wp\/v2\/media\/64861"}],"wp:attachment":[{"href":"https:\/\/blog.medel.com\/de\/wp-json\/wp\/v2\/media?parent=46849"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.medel.com\/de\/wp-json\/wp\/v2\/categories?post=46849"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.medel.com\/de\/wp-json\/wp\/v2\/tags?post=46849"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}