{"id":94635,"date":"2020-03-05T08:30:11","date_gmt":"2020-03-05T08:30:11","guid":{"rendered":"https:\/\/blog.medel.com\/%d8%ba%d9%8a%d8%b1-%d9%85%d8%b5%d9%86%d9%81\/what-is-a-cochlear-implant\/"},"modified":"2025-06-23T12:14:43","modified_gmt":"2025-06-23T10:14:43","slug":"%d9%85%d8%a7-%d9%87%d9%8a-%d8%b2%d8%b1%d8%b9%d8%a9-%d8%a7%d9%84%d9%82%d9%88%d9%82%d8%b9%d8%a9","status":"publish","type":"post","link":"https:\/\/blog.medel.com\/ar\/technology-ar\/%d9%85%d8%a7-%d9%87%d9%8a-%d8%b2%d8%b1%d8%b9%d8%a9-%d8%a7%d9%84%d9%82%d9%88%d9%82%d8%b9%d8%a9\/","title":{"rendered":"\u0645\u0627 \u0647\u064a \u0632\u0631\u0627\u0639\u0629 \u0627\u0644\u0642\u0648\u0642\u0639\u0629\u061f"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<p>\u0632\u0631\u0639\u0629 \u0627\u0644\u0642\u0648\u0642\u0639\u0629 \u0627\u0644\u0625\u0644\u0643\u062a\u0631\u0648\u0646\u064a\u0629 \u0647\u064a \u0646\u0648\u0639 \u0645\u0646 \u0627\u0644\u0632\u0631\u0639\u0627\u062a \u0627\u0644\u0633\u0645\u0639\u064a\u0629 \u0627\u0644\u062a\u064a \u062a\u0633\u0627\u0639\u062f \u0639\u0644\u0649 \u0627\u0644\u0633\u0645\u0627\u0639 \u0644\u0645\u0626\u0627\u062a \u0627\u0644\u0622\u0644\u0627\u0641 \u0645\u0646 \u0627\u0644\u0623\u0634\u062e\u0627\u0635 \u0643\u0644 \u064a\u0648\u0645. \u0644\u0643\u0646 \u0643\u064a\u0641 \u062a\u0639\u0645\u0644 \u0632\u0631\u0639\u0627\u062a \u0627\u0644\u0642\u0648\u0642\u0639\u0629 \u062a\u0645\u0627\u0645\u0627\u064b\u061f \u062a\u0627\u0628\u0639 \u0627\u0644\u0642\u0631\u0627\u0621\u0629 \u0644\u0645\u0639\u0631\u0641\u0629 \u0627\u0644\u0623\u0633\u0627\u0633\u064a\u0627\u062a \u0639\u0646 \u0632\u0631\u0639\u0627\u062a \u0627\u0644\u0642\u0648\u0642\u0639\u0629 \u0627\u0644\u0625\u0644\u0643\u062a\u0631\u0648\u0646\u064a\u0629: \u0645\u0627 \u0647\u064a\u060c \u0648\u0643\u064a\u0641 \u062a\u0639\u0645\u0644\u060c \u0648\u0645\u0646 \u0627\u0644\u0630\u064a \u064a\u0645\u0643\u0646\u0647 \u0627\u0644\u0627\u0633\u062a\u0641\u0627\u062f\u0629 \u0645\u0646 \u0632\u0631\u0639\u0629 \u0627\u0644\u0642\u0648\u0642\u0639\u0629.<\/p>\n","protected":false},"author":8,"featured_media":88779,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4031],"tags":[4115,4121,4194,4198,4098,4155,4108,4267,4099,4102,4193,4266,4268,4103,4158],"class_list":["post-94635","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-technology-ar","tag-cochlear-implant-ar","tag-hearing-loss-ar","tag-4194","tag-4198","tag-4098","tag-4155","tag-4108","tag-4267","tag-4099","tag-4102","tag-4193","tag-4266","tag-4268","tag-4103","tag-4158"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u0645\u0627 \u0647\u064a \u0632\u0631\u0627\u0639\u0629 \u0627\u0644\u0642\u0648\u0642\u0639\u0629\u061f - The MED-EL Blog<\/title>\n<meta name=\"description\" content=\".\u0644\u0645\u0639\u0631\u0641\u0629 \u0627\u0644\u0623\u0633\u0627\u0633\u064a\u0627\u062a \u0639\u0646 \u0632\u0631\u0639\u0627\u062a \u0627\u0644\u0642\u0648\u0642\u0639\u0629 \u0627\u0644\u0625\u0644\u0643\u062a\u0631\u0648\u0646\u064a\u0629: \u0645\u0627 \u0647\u064a\u060c \u0648\u0643\u064a\u0641 \u062a\u0639\u0645\u0644\u060c \u0648\u0645\u0646 \u0627\u0644\u0630\u064a \u064a\u0645\u0643\u0646\u0647 \u0627\u0644\u0627\u0633\u062a\u0641\u0627\u062f\u0629 \u0645\u0646 \u0632\u0631\u0639\u0629 \u0627\u0644\u0642\u0648\u0642\u0639\u0629 \u0627\u0644\u0625\u0644\u0643\u062a\u0631\u0648\u0646\u064a\u0629\u060c \u062a\u0635\u0641\u062d \u0647\u0630\u0627 \u0627\u0644\u0645\u0642\u0627\u0644 \u0644\u062a\u0639\u0631\u0641 \u0623\u0643\u062b\u0631.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/blog.medel.com\/ar\/technology-ar\/\u0645\u0627-\u0647\u064a-\u0632\u0631\u0639\u0629-\u0627\u0644\u0642\u0648\u0642\u0639\u0629\/\" \/>\n<meta property=\"og:locale\" content=\"ar_AR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u0645\u0627 \u0647\u064a \u0632\u0631\u0627\u0639\u0629 \u0627\u0644\u0642\u0648\u0642\u0639\u0629\u061f - The MED-EL Blog\" \/>\n<meta property=\"og:description\" content=\".\u0644\u0645\u0639\u0631\u0641\u0629 \u0627\u0644\u0623\u0633\u0627\u0633\u064a\u0627\u062a \u0639\u0646 \u0632\u0631\u0639\u0627\u062a \u0627\u0644\u0642\u0648\u0642\u0639\u0629 \u0627\u0644\u0625\u0644\u0643\u062a\u0631\u0648\u0646\u064a\u0629: \u0645\u0627 \u0647\u064a\u060c \u0648\u0643\u064a\u0641 \u062a\u0639\u0645\u0644\u060c \u0648\u0645\u0646 \u0627\u0644\u0630\u064a \u064a\u0645\u0643\u0646\u0647 \u0627\u0644\u0627\u0633\u062a\u0641\u0627\u062f\u0629 \u0645\u0646 \u0632\u0631\u0639\u0629 \u0627\u0644\u0642\u0648\u0642\u0639\u0629 \u0627\u0644\u0625\u0644\u0643\u062a\u0631\u0648\u0646\u064a\u0629\u060c \u062a\u0635\u0641\u062d \u0647\u0630\u0627 \u0627\u0644\u0645\u0642\u0627\u0644 \u0644\u062a\u0639\u0631\u0641 \u0623\u0643\u062b\u0631.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/blog.medel.com\/ar\/technology-ar\/\u0645\u0627-\u0647\u064a-\u0632\u0631\u0639\u0629-\u0627\u0644\u0642\u0648\u0642\u0639\u0629\/\" \/>\n<meta property=\"og:site_name\" content=\"The MED-EL Blog\" \/>\n<meta property=\"article:published_time\" content=\"2020-03-05T08:30:11+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-06-23T10:14:43+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/blog.medel.com\/wp-content\/uploads\/2023\/03\/sync2-blog.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"400\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"MED-EL\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u0643\u064f\u062a\u0628 \u0628\u0648\u0627\u0633\u0637\u0629\" \/>\n\t<meta name=\"twitter:data1\" content=\"MED-EL\" \/>\n\t<meta name=\"twitter:label2\" content=\"\u0648\u0642\u062a \u0627\u0644\u0642\u0631\u0627\u0621\u0629 \u0627\u0644\u0645\u064f\u0642\u062f\u0651\u0631\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 \u062f\u0642\u0627\u0626\u0642\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/blog.medel.com\\\/ar\\\/technology-ar\\\/%d9%85%d8%a7-%d9%87%d9%8a-%d8%b2%d8%b1%d8%b9%d8%a9-%d8%a7%d9%84%d9%82%d9%88%d9%82%d8%b9%d8%a9\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blog.medel.com\\\/ar\\\/technology-ar\\\/%d9%85%d8%a7-%d9%87%d9%8a-%d8%b2%d8%b1%d8%b9%d8%a9-%d8%a7%d9%84%d9%82%d9%88%d9%82%d8%b9%d8%a9\\\/\"},\"author\":{\"name\":\"MED-EL\",\"@id\":\"https:\\\/\\\/blog.medel.com\\\/de\\\/#\\\/schema\\\/person\\\/9f8dcfb27ec87796d874e021602c56e2\"},\"headline\":\"\u0645\u0627 \u0647\u064a \u0632\u0631\u0627\u0639\u0629 \u0627\u0644\u0642\u0648\u0642\u0639\u0629\u061f\",\"datePublished\":\"2020-03-05T08:30:11+00:00\",\"dateModified\":\"2025-06-23T10:14:43+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/blog.medel.com\\\/ar\\\/technology-ar\\\/%d9%85%d8%a7-%d9%87%d9%8a-%d8%b2%d8%b1%d8%b9%d8%a9-%d8%a7%d9%84%d9%82%d9%88%d9%82%d8%b9%d8%a9\\\/\"},\"wordCount\":0,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/blog.medel.com\\\/de\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/blog.medel.com\\\/ar\\\/technology-ar\\\/%d9%85%d8%a7-%d9%87%d9%8a-%d8%b2%d8%b1%d8%b9%d8%a9-%d8%a7%d9%84%d9%82%d9%88%d9%82%d8%b9%d8%a9\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/blog.medel.com\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/sync2-blog.jpg\",\"keywords\":[\"cochlear implant\",\"hearing loss\",\"\u0623\u0630\u0646\",\"\u0623\u0635\u0645\",\"\u0627\u0644\u0633\u0645\u0639\",\"\u0627\u0644\u063a\u0631\u0633\u0629 \u0627\u0644\u0633\u0645\u0639\u064a\u0629\",\"\u0627\u0644\u0642\u0648\u0642\u0639\u0629\",\"\u062d\u0644 \u0633\u0645\u0639\u064a\",\"\u0632\u0631\u0627\u0639\u0629 \u0627\u0644\u0642\u0648\u0642\u0639\u0629\",\"\u0636\u0639\u0641 \u0627\u0644\u0633\u0645\u0639\",\"\u0637\u0628\u064a\u0628\",\"\u0641\u0627\u0642\u062f \u0627\u0644\u0633\u0645\u0639\",\"\u0641\u062d\u0635 \u0633\u0645\u0639\u064a\",\"\u0641\u0642\u062f\u0627\u0646 \u0627\u0644\u0633\u0645\u0639\",\"\u0645\u064a\u062f\u0626\u0644\"],\"articleSection\":[\"\u0627\u0644\u062a\u0643\u0646\u0648\u0644\u0648\u062c\u064a\u0627\"],\"inLanguage\":\"ar\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/blog.medel.com\\\/ar\\\/technology-ar\\\/%d9%85%d8%a7-%d9%87%d9%8a-%d8%b2%d8%b1%d8%b9%d8%a9-%d8%a7%d9%84%d9%82%d9%88%d9%82%d8%b9%d8%a9\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/blog.medel.com\\\/ar\\\/technology-ar\\\/%d9%85%d8%a7-%d9%87%d9%8a-%d8%b2%d8%b1%d8%b9%d8%a9-%d8%a7%d9%84%d9%82%d9%88%d9%82%d8%b9%d8%a9\\\/\",\"url\":\"https:\\\/\\\/blog.medel.com\\\/ar\\\/technology-ar\\\/%d9%85%d8%a7-%d9%87%d9%8a-%d8%b2%d8%b1%d8%b9%d8%a9-%d8%a7%d9%84%d9%82%d9%88%d9%82%d8%b9%d8%a9\\\/\",\"name\":\"\u0645\u0627 \u0647\u064a \u0632\u0631\u0627\u0639\u0629 \u0627\u0644\u0642\u0648\u0642\u0639\u0629\u061f - The MED-EL Blog\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blog.medel.com\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/blog.medel.com\\\/ar\\\/technology-ar\\\/%d9%85%d8%a7-%d9%87%d9%8a-%d8%b2%d8%b1%d8%b9%d8%a9-%d8%a7%d9%84%d9%82%d9%88%d9%82%d8%b9%d8%a9\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/blog.medel.com\\\/ar\\\/technology-ar\\\/%d9%85%d8%a7-%d9%87%d9%8a-%d8%b2%d8%b1%d8%b9%d8%a9-%d8%a7%d9%84%d9%82%d9%88%d9%82%d8%b9%d8%a9\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/blog.medel.com\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/sync2-blog.jpg\",\"datePublished\":\"2020-03-05T08:30:11+00:00\",\"dateModified\":\"2025-06-23T10:14:43+00:00\",\"description\":\".\u0644\u0645\u0639\u0631\u0641\u0629 \u0627\u0644\u0623\u0633\u0627\u0633\u064a\u0627\u062a \u0639\u0646 \u0632\u0631\u0639\u0627\u062a \u0627\u0644\u0642\u0648\u0642\u0639\u0629 \u0627\u0644\u0625\u0644\u0643\u062a\u0631\u0648\u0646\u064a\u0629: \u0645\u0627 \u0647\u064a\u060c \u0648\u0643\u064a\u0641 \u062a\u0639\u0645\u0644\u060c \u0648\u0645\u0646 \u0627\u0644\u0630\u064a \u064a\u0645\u0643\u0646\u0647 \u0627\u0644\u0627\u0633\u062a\u0641\u0627\u062f\u0629 \u0645\u0646 \u0632\u0631\u0639\u0629 \u0627\u0644\u0642\u0648\u0642\u0639\u0629 \u0627\u0644\u0625\u0644\u0643\u062a\u0631\u0648\u0646\u064a\u0629\u060c \u062a\u0635\u0641\u062d \u0647\u0630\u0627 \u0627\u0644\u0645\u0642\u0627\u0644 \u0644\u062a\u0639\u0631\u0641 \u0623\u0643\u062b\u0631.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/blog.medel.com\\\/ar\\\/technology-ar\\\/%d9%85%d8%a7-%d9%87%d9%8a-%d8%b2%d8%b1%d8%b9%d8%a9-%d8%a7%d9%84%d9%82%d9%88%d9%82%d8%b9%d8%a9\\\/#breadcrumb\"},\"inLanguage\":\"ar\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/blog.medel.com\\\/ar\\\/technology-ar\\\/%d9%85%d8%a7-%d9%87%d9%8a-%d8%b2%d8%b1%d8%b9%d8%a9-%d8%a7%d9%84%d9%82%d9%88%d9%82%d8%b9%d8%a9\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"ar\",\"@id\":\"https:\\\/\\\/blog.medel.com\\\/ar\\\/technology-ar\\\/%d9%85%d8%a7-%d9%87%d9%8a-%d8%b2%d8%b1%d8%b9%d8%a9-%d8%a7%d9%84%d9%82%d9%88%d9%82%d8%b9%d8%a9\\\/#primaryimage\",\"url\":\"https:\\\/\\\/blog.medel.com\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/sync2-blog.jpg\",\"contentUrl\":\"https:\\\/\\\/blog.medel.com\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/sync2-blog.jpg\",\"width\":800,\"height\":400},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/blog.medel.com\\\/ar\\\/technology-ar\\\/%d9%85%d8%a7-%d9%87%d9%8a-%d8%b2%d8%b1%d8%b9%d8%a9-%d8%a7%d9%84%d9%82%d9%88%d9%82%d8%b9%d8%a9\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/blog.medel.com\\\/ar\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u0645\u0627 \u0647\u064a \u0632\u0631\u0627\u0639\u0629 \u0627\u0644\u0642\u0648\u0642\u0639\u0629\u061f\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/blog.medel.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/blog.medel.com\\\/de\\\/\",\"name\":\"The MED-EL Blog\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/blog.medel.com\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/blog.medel.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ar\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/blog.medel.com\\\/de\\\/#organization\",\"name\":\"The MED-EL Blog\",\"url\":\"https:\\\/\\\/blog.medel.com\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ar\",\"@id\":\"https:\\\/\\\/blog.medel.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/blog.medel.com\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/MED-EL_logo_L2.png\",\"contentUrl\":\"https:\\\/\\\/blog.medel.com\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/MED-EL_logo_L2.png\",\"width\":443,\"height\":200,\"caption\":\"The MED-EL Blog\"},\"image\":{\"@id\":\"https:\\\/\\\/blog.medel.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/blog.medel.com\\\/de\\\/#\\\/schema\\\/person\\\/9f8dcfb27ec87796d874e021602c56e2\",\"name\":\"MED-EL\",\"sameAs\":[\"https:\\\/\\\/www.medel.com\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u0645\u0627 \u0647\u064a \u0632\u0631\u0627\u0639\u0629 \u0627\u0644\u0642\u0648\u0642\u0639\u0629\u061f - The MED-EL Blog","description":".\u0644\u0645\u0639\u0631\u0641\u0629 \u0627\u0644\u0623\u0633\u0627\u0633\u064a\u0627\u062a \u0639\u0646 \u0632\u0631\u0639\u0627\u062a \u0627\u0644\u0642\u0648\u0642\u0639\u0629 \u0627\u0644\u0625\u0644\u0643\u062a\u0631\u0648\u0646\u064a\u0629: \u0645\u0627 \u0647\u064a\u060c \u0648\u0643\u064a\u0641 \u062a\u0639\u0645\u0644\u060c \u0648\u0645\u0646 \u0627\u0644\u0630\u064a \u064a\u0645\u0643\u0646\u0647 \u0627\u0644\u0627\u0633\u062a\u0641\u0627\u062f\u0629 \u0645\u0646 \u0632\u0631\u0639\u0629 \u0627\u0644\u0642\u0648\u0642\u0639\u0629 \u0627\u0644\u0625\u0644\u0643\u062a\u0631\u0648\u0646\u064a\u0629\u060c \u062a\u0635\u0641\u062d \u0647\u0630\u0627 \u0627\u0644\u0645\u0642\u0627\u0644 \u0644\u062a\u0639\u0631\u0641 \u0623\u0643\u062b\u0631.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/blog.medel.com\/ar\/technology-ar\/\u0645\u0627-\u0647\u064a-\u0632\u0631\u0639\u0629-\u0627\u0644\u0642\u0648\u0642\u0639\u0629\/","og_locale":"ar_AR","og_type":"article","og_title":"\u0645\u0627 \u0647\u064a \u0632\u0631\u0627\u0639\u0629 \u0627\u0644\u0642\u0648\u0642\u0639\u0629\u061f - The MED-EL Blog","og_description":".\u0644\u0645\u0639\u0631\u0641\u0629 \u0627\u0644\u0623\u0633\u0627\u0633\u064a\u0627\u062a \u0639\u0646 \u0632\u0631\u0639\u0627\u062a \u0627\u0644\u0642\u0648\u0642\u0639\u0629 \u0627\u0644\u0625\u0644\u0643\u062a\u0631\u0648\u0646\u064a\u0629: \u0645\u0627 \u0647\u064a\u060c \u0648\u0643\u064a\u0641 \u062a\u0639\u0645\u0644\u060c \u0648\u0645\u0646 \u0627\u0644\u0630\u064a \u064a\u0645\u0643\u0646\u0647 \u0627\u0644\u0627\u0633\u062a\u0641\u0627\u062f\u0629 \u0645\u0646 \u0632\u0631\u0639\u0629 \u0627\u0644\u0642\u0648\u0642\u0639\u0629 \u0627\u0644\u0625\u0644\u0643\u062a\u0631\u0648\u0646\u064a\u0629\u060c \u062a\u0635\u0641\u062d \u0647\u0630\u0627 \u0627\u0644\u0645\u0642\u0627\u0644 \u0644\u062a\u0639\u0631\u0641 \u0623\u0643\u062b\u0631.","og_url":"https:\/\/blog.medel.com\/ar\/technology-ar\/\u0645\u0627-\u0647\u064a-\u0632\u0631\u0639\u0629-\u0627\u0644\u0642\u0648\u0642\u0639\u0629\/","og_site_name":"The MED-EL Blog","article_published_time":"2020-03-05T08:30:11+00:00","article_modified_time":"2025-06-23T10:14:43+00:00","og_image":[{"width":800,"height":400,"url":"https:\/\/blog.medel.com\/wp-content\/uploads\/2023\/03\/sync2-blog.jpg","type":"image\/jpeg"}],"author":"MED-EL","twitter_card":"summary_large_image","twitter_misc":{"\u0643\u064f\u062a\u0628 \u0628\u0648\u0627\u0633\u0637\u0629":"MED-EL","\u0648\u0642\u062a \u0627\u0644\u0642\u0631\u0627\u0621\u0629 \u0627\u0644\u0645\u064f\u0642\u062f\u0651\u0631":"4 \u062f\u0642\u0627\u0626\u0642"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/blog.medel.com\/ar\/technology-ar\/%d9%85%d8%a7-%d9%87%d9%8a-%d8%b2%d8%b1%d8%b9%d8%a9-%d8%a7%d9%84%d9%82%d9%88%d9%82%d8%b9%d8%a9\/#article","isPartOf":{"@id":"https:\/\/blog.medel.com\/ar\/technology-ar\/%d9%85%d8%a7-%d9%87%d9%8a-%d8%b2%d8%b1%d8%b9%d8%a9-%d8%a7%d9%84%d9%82%d9%88%d9%82%d8%b9%d8%a9\/"},"author":{"name":"MED-EL","@id":"https:\/\/blog.medel.com\/de\/#\/schema\/person\/9f8dcfb27ec87796d874e021602c56e2"},"headline":"\u0645\u0627 \u0647\u064a \u0632\u0631\u0627\u0639\u0629 \u0627\u0644\u0642\u0648\u0642\u0639\u0629\u061f","datePublished":"2020-03-05T08:30:11+00:00","dateModified":"2025-06-23T10:14:43+00:00","mainEntityOfPage":{"@id":"https:\/\/blog.medel.com\/ar\/technology-ar\/%d9%85%d8%a7-%d9%87%d9%8a-%d8%b2%d8%b1%d8%b9%d8%a9-%d8%a7%d9%84%d9%82%d9%88%d9%82%d8%b9%d8%a9\/"},"wordCount":0,"commentCount":0,"publisher":{"@id":"https:\/\/blog.medel.com\/de\/#organization"},"image":{"@id":"https:\/\/blog.medel.com\/ar\/technology-ar\/%d9%85%d8%a7-%d9%87%d9%8a-%d8%b2%d8%b1%d8%b9%d8%a9-%d8%a7%d9%84%d9%82%d9%88%d9%82%d8%b9%d8%a9\/#primaryimage"},"thumbnailUrl":"https:\/\/blog.medel.com\/wp-content\/uploads\/2023\/03\/sync2-blog.jpg","keywords":["cochlear implant","hearing loss","\u0623\u0630\u0646","\u0623\u0635\u0645","\u0627\u0644\u0633\u0645\u0639","\u0627\u0644\u063a\u0631\u0633\u0629 \u0627\u0644\u0633\u0645\u0639\u064a\u0629","\u0627\u0644\u0642\u0648\u0642\u0639\u0629","\u062d\u0644 \u0633\u0645\u0639\u064a","\u0632\u0631\u0627\u0639\u0629 \u0627\u0644\u0642\u0648\u0642\u0639\u0629","\u0636\u0639\u0641 \u0627\u0644\u0633\u0645\u0639","\u0637\u0628\u064a\u0628","\u0641\u0627\u0642\u062f \u0627\u0644\u0633\u0645\u0639","\u0641\u062d\u0635 \u0633\u0645\u0639\u064a","\u0641\u0642\u062f\u0627\u0646 \u0627\u0644\u0633\u0645\u0639","\u0645\u064a\u062f\u0626\u0644"],"articleSection":["\u0627\u0644\u062a\u0643\u0646\u0648\u0644\u0648\u062c\u064a\u0627"],"inLanguage":"ar","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/blog.medel.com\/ar\/technology-ar\/%d9%85%d8%a7-%d9%87%d9%8a-%d8%b2%d8%b1%d8%b9%d8%a9-%d8%a7%d9%84%d9%82%d9%88%d9%82%d8%b9%d8%a9\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/blog.medel.com\/ar\/technology-ar\/%d9%85%d8%a7-%d9%87%d9%8a-%d8%b2%d8%b1%d8%b9%d8%a9-%d8%a7%d9%84%d9%82%d9%88%d9%82%d8%b9%d8%a9\/","url":"https:\/\/blog.medel.com\/ar\/technology-ar\/%d9%85%d8%a7-%d9%87%d9%8a-%d8%b2%d8%b1%d8%b9%d8%a9-%d8%a7%d9%84%d9%82%d9%88%d9%82%d8%b9%d8%a9\/","name":"\u0645\u0627 \u0647\u064a \u0632\u0631\u0627\u0639\u0629 \u0627\u0644\u0642\u0648\u0642\u0639\u0629\u061f - The MED-EL Blog","isPartOf":{"@id":"https:\/\/blog.medel.com\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/blog.medel.com\/ar\/technology-ar\/%d9%85%d8%a7-%d9%87%d9%8a-%d8%b2%d8%b1%d8%b9%d8%a9-%d8%a7%d9%84%d9%82%d9%88%d9%82%d8%b9%d8%a9\/#primaryimage"},"image":{"@id":"https:\/\/blog.medel.com\/ar\/technology-ar\/%d9%85%d8%a7-%d9%87%d9%8a-%d8%b2%d8%b1%d8%b9%d8%a9-%d8%a7%d9%84%d9%82%d9%88%d9%82%d8%b9%d8%a9\/#primaryimage"},"thumbnailUrl":"https:\/\/blog.medel.com\/wp-content\/uploads\/2023\/03\/sync2-blog.jpg","datePublished":"2020-03-05T08:30:11+00:00","dateModified":"2025-06-23T10:14:43+00:00","description":".\u0644\u0645\u0639\u0631\u0641\u0629 \u0627\u0644\u0623\u0633\u0627\u0633\u064a\u0627\u062a \u0639\u0646 \u0632\u0631\u0639\u0627\u062a \u0627\u0644\u0642\u0648\u0642\u0639\u0629 \u0627\u0644\u0625\u0644\u0643\u062a\u0631\u0648\u0646\u064a\u0629: \u0645\u0627 \u0647\u064a\u060c \u0648\u0643\u064a\u0641 \u062a\u0639\u0645\u0644\u060c \u0648\u0645\u0646 \u0627\u0644\u0630\u064a \u064a\u0645\u0643\u0646\u0647 \u0627\u0644\u0627\u0633\u062a\u0641\u0627\u062f\u0629 \u0645\u0646 \u0632\u0631\u0639\u0629 \u0627\u0644\u0642\u0648\u0642\u0639\u0629 \u0627\u0644\u0625\u0644\u0643\u062a\u0631\u0648\u0646\u064a\u0629\u060c \u062a\u0635\u0641\u062d \u0647\u0630\u0627 \u0627\u0644\u0645\u0642\u0627\u0644 \u0644\u062a\u0639\u0631\u0641 \u0623\u0643\u062b\u0631.","breadcrumb":{"@id":"https:\/\/blog.medel.com\/ar\/technology-ar\/%d9%85%d8%a7-%d9%87%d9%8a-%d8%b2%d8%b1%d8%b9%d8%a9-%d8%a7%d9%84%d9%82%d9%88%d9%82%d8%b9%d8%a9\/#breadcrumb"},"inLanguage":"ar","potentialAction":[{"@type":"ReadAction","target":["https:\/\/blog.medel.com\/ar\/technology-ar\/%d9%85%d8%a7-%d9%87%d9%8a-%d8%b2%d8%b1%d8%b9%d8%a9-%d8%a7%d9%84%d9%82%d9%88%d9%82%d8%b9%d8%a9\/"]}]},{"@type":"ImageObject","inLanguage":"ar","@id":"https:\/\/blog.medel.com\/ar\/technology-ar\/%d9%85%d8%a7-%d9%87%d9%8a-%d8%b2%d8%b1%d8%b9%d8%a9-%d8%a7%d9%84%d9%82%d9%88%d9%82%d8%b9%d8%a9\/#primaryimage","url":"https:\/\/blog.medel.com\/wp-content\/uploads\/2023\/03\/sync2-blog.jpg","contentUrl":"https:\/\/blog.medel.com\/wp-content\/uploads\/2023\/03\/sync2-blog.jpg","width":800,"height":400},{"@type":"BreadcrumbList","@id":"https:\/\/blog.medel.com\/ar\/technology-ar\/%d9%85%d8%a7-%d9%87%d9%8a-%d8%b2%d8%b1%d8%b9%d8%a9-%d8%a7%d9%84%d9%82%d9%88%d9%82%d8%b9%d8%a9\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/blog.medel.com\/ar\/"},{"@type":"ListItem","position":2,"name":"\u0645\u0627 \u0647\u064a \u0632\u0631\u0627\u0639\u0629 \u0627\u0644\u0642\u0648\u0642\u0639\u0629\u061f"}]},{"@type":"WebSite","@id":"https:\/\/blog.medel.com\/de\/#website","url":"https:\/\/blog.medel.com\/de\/","name":"The MED-EL Blog","description":"","publisher":{"@id":"https:\/\/blog.medel.com\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/blog.medel.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ar"},{"@type":"Organization","@id":"https:\/\/blog.medel.com\/de\/#organization","name":"The MED-EL Blog","url":"https:\/\/blog.medel.com\/de\/","logo":{"@type":"ImageObject","inLanguage":"ar","@id":"https:\/\/blog.medel.com\/de\/#\/schema\/logo\/image\/","url":"https:\/\/blog.medel.com\/wp-content\/uploads\/2023\/02\/MED-EL_logo_L2.png","contentUrl":"https:\/\/blog.medel.com\/wp-content\/uploads\/2023\/02\/MED-EL_logo_L2.png","width":443,"height":200,"caption":"The MED-EL Blog"},"image":{"@id":"https:\/\/blog.medel.com\/de\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/blog.medel.com\/de\/#\/schema\/person\/9f8dcfb27ec87796d874e021602c56e2","name":"MED-EL","sameAs":["https:\/\/www.medel.com"]}]}},"_links":{"self":[{"href":"https:\/\/blog.medel.com\/ar\/wp-json\/wp\/v2\/posts\/94635","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.medel.com\/ar\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.medel.com\/ar\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.medel.com\/ar\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.medel.com\/ar\/wp-json\/wp\/v2\/comments?post=94635"}],"version-history":[{"count":2,"href":"https:\/\/blog.medel.com\/ar\/wp-json\/wp\/v2\/posts\/94635\/revisions"}],"predecessor-version":[{"id":94639,"href":"https:\/\/blog.medel.com\/ar\/wp-json\/wp\/v2\/posts\/94635\/revisions\/94639"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blog.medel.com\/ar\/wp-json\/wp\/v2\/media\/88779"}],"wp:attachment":[{"href":"https:\/\/blog.medel.com\/ar\/wp-json\/wp\/v2\/media?parent=94635"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.medel.com\/ar\/wp-json\/wp\/v2\/categories?post=94635"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.medel.com\/ar\/wp-json\/wp\/v2\/tags?post=94635"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}